{"id":8647,"date":"2021-02-17T16:42:36","date_gmt":"2021-02-17T16:42:36","guid":{"rendered":"http:\/\/www.therwandan.com\/fr\/?p=8647"},"modified":"2021-02-17T16:51:13","modified_gmt":"2021-02-17T16:51:13","slug":"discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais","status":"publish","type":"post","link":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/","title":{"rendered":"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>60 ans apr\u00e8s la r\u00e9volution rwandaise de 1959, une deuxi\u00e8me r\u00e9volution est d\u00e9clench\u00e9e par le discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryamugwiza. C\u2019\u00e9tait le 31 Janvier 2021, en deux semaines seulement, son discours sur sa chaine YouTube a battu tous les records rwandais avec plus de 200 000 visionnements. Pour le monde entier et pour les amis du Rwanda francophones, il me fait un grand plaisir de traduire en fran\u00e7ais le discours int\u00e9gral de Mme Yvonne Idamange Iryabagwiza.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_54448\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/KcOy7buDWt0?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais par Jotham Rwamiheto, vivant \u00e0 Montr\u00e9al, au Canada.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bonjour Mesdames et Messieurs, les Rwandais. Je suis heureuse d\u2019avoir cette opportunit\u00e9 d\u2019interagir avec vous. Mais permettez-moi d\u2019abord de me pr\u00e9senter, car il est bon que les gens se connaissent avant d\u2019entretenir une conversation. Ce n\u2019est pas bien que je vienne simplement et que je commence \u00e0 vous parler sans me pr\u00e9senter \u00e0 vous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je suis Idamange Iryamugwiza Yvonne, je reste dans la ville de Kigali, dans le district de Gasabo dans le secteur de Kimironko, je suis rwandaise. Dans ma vie ordinaire, je suis n\u00e9e dans le district de Kamonyi, dans la province du sud, dans le secteur de Rugarika, appel\u00e9 commun\u00e9ment Kigezi. C\u2019est l\u00e0 que j\u2019ai fait mes \u00e9tudes primaires. J\u2019ai ensuite poursuivi mes \u00e9tudes secondaires \u00e0 Kansi, \u00e0 Butare, et j\u2019ai obtenu mon dipl\u00f4me de l\u2019ECOS Musambira. C\u2019est l\u00e0 que j\u2019ai termin\u00e9 mes \u00e9tudes secondaires. J\u2019ai poursuivi mes \u00e9tudes universitaires \u00e0 Kigali Institute of Management (KIM), et j\u2019ai fait mon Master \u00e0 l\u2019ULK. Je suis parent et m\u00e8re de 4 enfants.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je voudrais vous parler en tant que mes compatriotes rwandais, et en tant qu\u2019une femme rwandaise qui aime mon pays et qui lutte pour la fiert\u00e9 de mes compatriotes rwandais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a quelques points cl\u00e9s sur lesquels je voudrais me concentrer maintenant pendant que je vous parle, je souhaite que nous abordions beaucoup de choses mais je ne peux pas tout finir en m\u00eame temps. Il y a des points cl\u00e9s que je veux vraiment que nous abordions :<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier point dont je souhaite que nous parlions est celui du droit de vivre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le deuxi\u00e8me point concerne l\u2019\u00e9ducation au Rwanda.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le troisi\u00e8me point concerne la libert\u00e9 religieuse pour les Rwandais.Le quatri\u00e8me point, qui sera probablement le dernier, est de savoir si nous, lesRwandais, ne sommes pas conduits comme des moutons sans berger!Permettez-moi de commencer par le premier point sur le droit de vivre tel qu\u2019il est n\u00e9cessaire \u00e0 un \u00eatre humain. Peut-\u00eatre que beaucoup pourraient se demander pourquoi je vous parle du droit de vivre comme si nous ne vivions pas. Il y a vivre juste en faisant semblant de vivre, mais il y a aussi vivre en vivant comme il faut. Dans le droit de vivre que nous avons en tant qu\u2019humains, il y a le droit que nous avons obtenu de Dieu, qu\u2019aucun \u00eatre humain ne devrait nous en emp\u00eacher. Disons par exemple le droit de respirer. C\u2019est seulement Dieu qui nous donne l\u2019oxyg\u00e8ne que nous respirons. Personne ne peut vous emp\u00eacher de respirer, \u00e0 part Dieu qui vous a donn\u00e9 ce droit.Maintenant, comme je choisis qu\u2019on parle du droit de vivre comme il faut, dans notre pays, c\u2019est parce qu\u2019il y a longtemps qu\u2019on a des probl\u00e8mes, c\u2019est m\u00eame partout dans le monde, li\u00e9s \u00e0 la pand\u00e9mie de coronavirus, mais tr\u00e8s souvent, pour nous Rwandais, nous ne parvenons pas \u00e0 y faire face. Comme juste pour la premi\u00e8re fois, nous exhortons automatiquement les citoyens \u00e0 rester chez eux. Demander aux gens de rester \u00e0 la maison pendant que les gens ne se sont pas pr\u00e9par\u00e9s, nous pouvons le comparer \u00e0 une pluie qui tombe soudainement alors que les gens n\u2019ont vu aucun signe qu\u2019il va pleuvoir.Seul le Conseil du Cabinet a lieu et ils d\u00e9cident du jour au lendemain que tous les Rwandais doivent rester chez eux. De telles d\u00e9cisions sont prises tard dans la nuit, lorsque certaines personnes dorment d\u00e9j\u00e0, ont des programmes le matin, le jour suivant. Lorsqu\u2019elles se r\u00e9veillent, elles se rendent compte que tous les programmes ont chang\u00e9. Ces d\u00e9cisions sont prises alors qu\u2019il y a des citoyens qui n\u2019ont pas pris le temps de collecter des fonds, et qui n\u2019ont par la suite, pas m\u00eame un sous \u00e0 la maison pour s\u2019occuper de la famille. Ces d\u00e9cisions sont prises tard dans la nuit.A vrai dire, je ne suis pas venu ici pour m\u2019opposer au fait que les Rwandais doivent lutter contre le coronavirus. Non, c\u2019est une pand\u00e9mie qui est r\u00e9elle, je l\u2019accepte, mais ce que je demande \u00e0 notre gouvernement du Rwanda, c\u2019est que, nous soyons capables de lutter contre le coronavirus et le g\u00e9rer avec succ\u00e8s, au lieu de le laisser nous g\u00e9rer, nous pousser \u00e0 rester cach\u00e9s chez nous, nous faire vivre sous pression; et tout d\u2019un coup, la vie des citoyens s\u2019arr\u00eate \u00e0 cause du coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est vrai que je suis d\u2019accord avec le fait de se laver les mains et de respecter les mesures de distanciation sociale et de ne pas se disperser partout, mais sans toutefois oublier la vie des Rwandais. Si le Conseil du Cabinet d\u00e9cide que les Rwandais doivent rester chez eux en ignorant qu\u2019il y a des Rwandais qui n\u2019ont pas \u00e0 manger, en ignorant que les Rwandais trouvent de quoi manger parce qu\u2019ils sont sortis travailler, ce citoyen dont vous vous occupez face au coronavirus va mourir de faim. Quelle est l\u2019importance de cela? Vous dites que vous nous aidez, vous aidez les citoyens lorsque vous les incitez \u00e0 rester chez eux, que leur donnez-vous? La farine am\u00e8re pourrie? Laissez-moi vous dire qu\u2019ils ne peuvent m\u00eame pas faire du foufou (patte de ma\u00efs) avec cette farine. Au lieu de cela, ils font la bouillie parce qu\u2019il leur a \u00e9t\u00e9 impossible de faire une patte.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensez-vous vraiment que vous aidez ces citoyens ou que c\u2019est la punition?<br>Vous leur donnez un kilogramme de haricots, un kilogramme qu\u2019ils vont avoir du mal \u00e0 cuisiner. Ils vont devoir acheter du charbon de bois de 2000 RWF pour cuire 1 kg, aidez- vous vraiment ces citoyens ou vous les envoyez simplement rester \u00e0 la maison? Qu\u2019ils survivent ou meurent, vous ne vous en souciez pas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chers gestionnaires, ces denr\u00e9es alimentaires que vous donnez aux Rwandais, cette farine de ma\u00efs, ces haricots, y a-t-il quelqu\u2019un parmi vous qui peut les rapporter \u00e0 la maison et nourrir la famille avec? Il est n\u00e9cessaire que nous prenions des d\u00e9cisions en tenant compte de la vie des citoyens rwandais ordinaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les Rwandais n\u2019ont pas les m\u00eames normes de vie. Par cons\u00e9quent, il n\u2019est pas juste que l\u2019Europe d\u00e9cide d\u2019exhorter ses citoyens \u00e0 rester chez eux, l\u2019Am\u00e9rique pareil et le Rwanda fait de m\u00eame sans leur donner les moyens de subsistance de base. Lorsque ces pays obligent leurs citoyens \u00e0 rester chez eux, ils les nourrissent. Aucun citoyen ne peut mourir de faim. Peut-\u00eatre que certains d\u2019entre vous ne seront pas d\u2019accord avec cela. Par exemple, j\u2019ai entendu le ministre SHYAKA dire: \u00abJe pr\u00e9f\u00e8re mourir de faim que de mourir de coronavirus\u00bb. Mais Monsieur le ministre, quand pensez-vous que la faim vous tue, vraiment? Vous \u00eates le ministre, votre salaire mensuel est toujours l\u00e0, que vous travailliez ou non, que vous incitiez les citoyens \u00e0 rester \u00e0 la maison ou non, votre salaire est l\u00e0. Quand la faim vous tuera-t-elle? Vous ne faites du mal aux citoyens qu\u2019en disant que vous pr\u00e9f\u00e9rez mourir de faim plut\u00f4t que de mourir de coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019autres fois, vous dites que m\u00eame les vendeurs qui passent du temps \u00e0 se d\u00e9placer avec des paniers sur leurs \u00e9paules, nous devons les exhorter \u00e0 rester \u00e0 la maison, mais Ministre SHYAKA, laissez-moi vous demander, car vous n\u2019\u00eates pas n\u00e9 \u00e0 New York mais \u00eates n\u00e9 ici au Rwanda, comme nous tous. Ignorez-vous qu\u2019un citoyen ordinaire doit courir avec un panier sur l\u2019\u00e9paule pour survivre? S\u2019il n\u2019est pas en mesure de ramasser de la nourriture dans le magasin \u00e0 la maison, ou d\u2019acheter de la nourriture avec une voiture comme vous le faites, ils doivent se d\u00e9placer avec un panier sur l\u2019\u00e9paule pour survivre car c\u2019est ainsi que leur style de vie est, et nous ne pourrons jamais vivre le m\u00eame style de vie.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Rwanda n\u2019est pas seulement un pays de riches, mais c\u2019est plut\u00f4t un pays de riches et de pauvres. Nous devons avoir les m\u00eames droits. Les deux paquets de bananes dont vous parlez, ce n\u2019est que ce qu\u2019ils ont pu obtenir. S\u2019ils ont pu l\u2019obtenir, il y en a m\u00eame d\u2019autres qui n\u2019ont pas pu l\u2019obtenir; qui dorment \u00e0 la maison, mourant de faim. La raison pour laquelle vous le mentionnez est que vos enfants ont mang\u00e9, c\u2019est parce que vous n\u2019avez jamais ressenti la faim dont vous parlez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On demande \u00e0 ces gens ordinaires, quand ils sortent, o\u00f9 ils vont, mais vous, personne ne vous demande o\u00f9 vous allez. C\u2019est pourquoi vous sous-estimez les probl\u00e8mes des Rwandais. Ce sont des mots frustrants pour les Rwandais, ce ne sont pas les mots d\u2019un leader qui d\u00e9fend les Rwandais, vous le prononcez alors qu\u2019il y en a beaucoup qui ont faim et n\u2019ont aucune issue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par cons\u00e9quent, pour cette question d\u2019exhorter les Rwandais \u00e0 rester \u00e0 la maison, moi en tant que Rwandaise qui ose prendre la parole, car je sais qu\u2019il y en a tellement qui souhaitent dire quelque chose mais qui ont peur, moi en tant que Rwandaise qui a surmont\u00e9 la peur, je demande le gouvernement rwandais d\u2019ouvrir les portes afin que nous sortions et travaillions, que nous prenions soin de nous-m\u00eames sans d\u00e9pendre de petites quantit\u00e9s de nourritures que vous nous donnez, qui ne sont m\u00eame pas re\u00e7ues par tout le monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous demandons vraiment de nous ouvrir les portes afin que nous vivions chez nous et que nous sortions. Comme vous le Ministre SHYAKA, je continue de vous parler, je vous ai entendu dire aux gens de faire du sport \u00e0 la maison et de ne pas sortir. SHYAKA, qui vous a dit que tous les citoyens restent dans leurs propres concessions? Il y a des citoyens qui n\u2019ont pas leurs propres terrains assez grands pour pratiquer le sport \u00e0 l\u2019int\u00e9rieur. Et si le coronavirus vient et attaque les gens par les zones respiratoires, pourquoi nous emp\u00eachez-vous de respirer? Ces personnes vont \u00eatre victimes d\u2019autres maladies parce qu\u2019elles sont oblig\u00e9es de rester \u00e0 la maison.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous obligez les gens \u00e0 rester \u00e0 la maison pendant que leurs affaires vont mal, ils ont d\u00e9pens\u00e9 beaucoup d\u2019argent, ils doivent beaucoup d\u2019argent aux banques, demain les banques fonctionneront apr\u00e8s; vous, en tant que gouvernement, vous n\u2019avez jamais emp\u00each\u00e9 l\u2019Autorit\u00e9 fiscale du Rwanda de collecter des imp\u00f4ts. Les gens continuent de payer des imp\u00f4ts, ils doivent payer des loyers pour les espaces qu\u2019ils louent, et les banques viendront demain prendre leurs biens en raison de pr\u00eats impay\u00e9s. Comment pourront-ils dormir s\u2019ils sont enferm\u00e9s chez eux en attendant le coronavirus?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a une vie minimale de base que vous devez respecter pour laisser les gens vivre. Vous prenez des d\u00e9cisions qui ont \u00e9t\u00e9 prises par l\u2019Europe pour inciter les gens \u00e0 rester chez eux parce qu\u2019ils sont capables de les nourrir et vous faites de m\u00eame ici au Rwanda!<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons notre propre style de vie, nous savons comment nous vivons, c\u2019est tr\u00e8s diff\u00e9rent du style de vie des Europ\u00e9ens, encore une fois, nous devons nous rappeler que nous ne sommes plus sous leur colonisation. Nous devons tous savoir que nous ne sommes plus colonis\u00e9s de telle mani\u00e8re qu\u2019ils d\u00e9cident de prendre des d\u00e9cisions et que nous les mettons en \u0153uvre ici. S\u2019il en est ainsi, la d\u00e9mocratie pour laquelle nous nous battons n\u2019aurait aucune valeur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ce qui me concerne, en tant que Rwandaise qui aime le Rwanda mon pays, je voudrais vous demander, au nom de mes autres rwandais, de nous permettre de sortir. Si ce n\u2019est pas le cas, les gens mourront de d\u00e9pression. Ils rentreront chez eux, dormiront et r\u00e9fl\u00e9chiront aux probl\u00e8mes caus\u00e9s par le confinement et mourront de d\u00e9pression et de crises cardiaques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous savons que le coronavirus est une vraie maladie, mais s\u2019il vous pla\u00eet, n\u2019en faites pas un jeu, pardonnez-nous. Le coronavirus n\u2019est pas la seule maladie pand\u00e9mique qui \u00e9clate ici au Rwanda. Il y a eu d\u2019abord le cancer, il y a eu de nombreuses maladies qui ont tu\u00e9 beaucoup de gens, il y a eu le sida qui a co\u00fbt\u00e9 la vie \u00e0 de nombreuses personnes, mais il n\u2019y a jamais eu de verrouillage. S\u2019il vous pla\u00eet, ouvrez-nous des portes pour que nous sortions, travaillions, prenions soin de nos familles et luttions contre le coronavirus. Je vous en prie, pardonnez-nous, arr\u00eatez de nous mettre dans ces prisons pour des faits pour lesquels vous ne nous dites jamais les crimes que nous avons commis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous ne pouvons pas oublier qu\u2019il y a beaucoup de familles que vous avez s\u00e9par\u00e9es. Il y a des gens qui sont partis en province, il y en a d\u2019autres qui sont venus dans la ville de Kigali alors qu\u2019ils voulaient rentrer chez eux. Ces personnes ont \u00e9t\u00e9 s\u00e9par\u00e9es de leurs familles et c\u2019est leur droit de vivre avec les leurs. Je vous en prie, ne sous-estimez pas ce droit de la famille. Et veuillez consid\u00e9rer toute cette p\u00e9riode de perte et baisser toutes les taxes pour que les gens aient le temps de travailler, de reconstruire leur entreprise et ensuite de payer des imp\u00f4ts. Dire \u00e0 quelqu\u2019un de fermer l\u2019entreprise \u00e0 18 heures avant le verrouillage, puis de lui dire plus tard de payer toutes les taxes, d\u2019o\u00f9 vont-ils obtenir de l\u2019argent? S\u2019il vous pla\u00eet, prenez cela en compte et arr\u00eatez de dire qu\u2019il y a eu un Conseil du Cabinet et que de telles d\u00e9cisions ont \u00e9t\u00e9 prises, d\u00e9cisions selon lesquelles tous les citoyens doivent rester \u00e0 la maison, ce que vous nous dites d\u2019ailleurs avec beaucoup d\u2019arrogance et d\u2019humiliation \u00e0 notre \u00e9gard. Dites-le-nous plut\u00f4t en tant que Rwandais, en tant que pays fond\u00e9 sur la d\u00e9mocratie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre souhait est la justice. Nous souhaitons vivre de mani\u00e8re \u00e0 ce que chacun ait le droit de vivre. Ce point, je pourrais continuer \u00e0 en parler, mais ce que nous souhaitons, c\u2019est que vous nous ouvriez les portes pour que les gens sortent et travaillent et puissent vivre, et ne d\u00e9pendent pas seulement des articles que vous nous donnez, que vous ne pouvez pas consommer vous-m\u00eames et ne peuvent m\u00eame pas atteindre tous les citoyens pour que les Rwandais ne meurent pas de faim.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un autre point que je vais mentionner concerne l\u2019\u00e9ducation au Rwanda. C\u2019est le deuxi\u00e8me point. Mesdames et messieurs Rwandais, je n\u2019ai pas peur d\u2019en parler parce que je vous ai dit que je n\u2019avais pas peur. Je n\u2019ai pas peur des armes \u00e0 feu, car j\u2019ai dit que j\u2019avais une arme ici : ma Bible. Je n\u2019ai donc pas peur des armes \u00e0 feu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laissez-moi vous dire que le probl\u00e8me de l\u2019\u00e9ducation ici au Rwanda est tr\u00e8s pr\u00e9occupant. Et la principale raison pour laquelle il est inqui\u00e9tant, est qu\u2019il effraie une partie de la population alors que l\u2019autre ne l\u2019est pas. La partie qui n\u2019est pas inqui\u00e8te est celle qui a le pouvoir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand nous parlons d\u2019\u00e9ducation au Rwanda, de nombreuses personnes souffrent au plus profond de leur c\u0153ur parce que le secteur de l\u2019\u00e9ducation est mort il y a longtemps, pas aujourd\u2019hui. Il est mort le jour o\u00f9 quelqu\u2019un s\u2019est r\u00e9veill\u00e9 et a d\u00e9cid\u00e9, si c\u2019est \u00e0 partir de leurs r\u00eaves ou de leurs pens\u00e9es que maintenant j\u2019annule la langue fran\u00e7aise, maintenant les \u00e9l\u00e8ves seront \u00e9duqu\u00e9s en anglais. C\u2019\u00e9tait une menace tr\u00e8s forte pour l\u2019\u00e9ducation. Ce n\u2019est pas parce que nous ne voulions pas conna\u00eetre l\u2019anglais parce que nous savons qu\u2019il est susceptible de devenir la premi\u00e8re langue internationale. Non, mais une langue ne doit pas \u00eatre annul\u00e9e du jour au lendemain. C\u2019est un processus. Car, annuler une langue dans les \u00e9coles, alors que m\u00eame les enseignants susceptibles d\u2019enseigner la nouvelle langue ne la connaissent pas, honn\u00eatement qui \u00e9taient les Rwandais qui ont pu utiliser l\u2019anglais lorsque le fran\u00e7ais a \u00e9t\u00e9 annul\u00e9? Qui \u00e9taient les professeurs capables d\u2019enseigner l\u2019anglais dans les \u00e9coles? Il n\u2019y en avait pas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est ainsi que des Ougandais, des Kenyans et d\u2019autres \u00e9trangers sont venus dans notre pays et ont eu un impact n\u00e9gatif sur l\u2019\u00e9ducation de nos enfants, parce qu\u2019ils n\u2019avaient aucun esprit patriotique pour aimer notre pays et qu\u2019ils n\u2019\u00e9taient pas oblig\u00e9s de le faire. Ils leur apprenaient simplement ce qu\u2019ils voulaient, sans se soucier qu\u2019ils comprennent ou non. Ces enseignants n\u2019enseignaient que dans des \u00e9coles internationales en leur payant beaucoup d\u2019argent, pas dans les \u00e9coles publiques. Ainsi, nous pourrions r\u00e9aliser que le secteur de l\u2019\u00e9ducation est paralys\u00e9. Un citoyen a sa propre fa\u00e7on d\u2019enseigner aux enfants du pays, car ils d\u00e9cident de leur inculquer des connaissances pour les pr\u00e9parer \u00e0 ce qu\u2019ils viendront demain pour le d\u00e9veloppement du pays, mais un \u00e9tranger vient juste pour l\u2019argent. C\u2019est la seule raison pour laquelle ils viennent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouvez un Ougandais enseignant la g\u00e9ographie du Rwanda, o\u00f9 la conna\u00eet-il? Un enfant vous dira qu\u2019il a fait de la g\u00e9ographie et qu\u2019il a obtenu son dipl\u00f4me sans m\u00eame pouvoir vous dire une culture qui est cultiv\u00e9e dans son pays parce qu\u2019il a \u00e9t\u00e9 form\u00e9 par un ougandais ou tout autre \u00e9tranger. Ils sont venus et ils enseignent l\u2019histoire du Rwanda, o\u00f9 la connaissent-ils? Simplement parce que ce sont eux qui connaissent cette langue. Nous n\u2019allons pas nous attarder sur ce point, mais ce que je voulais vous dire, c\u2019est que le secteur de l\u2019\u00e9ducation est mort il y a longtemps. Au Rwanda, il est mort il y a longtemps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ministre peut \u00eatre nomm\u00e9 et remplac\u00e9, il y a m\u00eame ceux qui sont rest\u00e9s moins d\u2019un an. Un ministre est nomm\u00e9 et apporte son propre syst\u00e8me, un autre est nomm\u00e9 et apporte le sien, tout cela \u00e9tant appliqu\u00e9 \u00e0 la jeunesse rwandaise et \u00e0 son intelligence. Le secteur de l\u2019\u00e9ducation est devenu un terrain de jeu et vous avez oubli\u00e9 que vous jouez sur la jeunesse du Rwanda. Un pays qui n\u2019a pas d\u2019enfants n\u2019a aucune chance de se d\u00e9velopper et vous oubliez que la jeunesse est le Rwanda de demain. Vous avez oubli\u00e9 que vous qui faites cela vieillissez et que les jeunes avec lesquels vous jouez sont ceux qui viendront vous remplacer et d\u00e9velopper le pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le secteur de l\u2019\u00e9ducation est en train de mourir, et la raison en est que les enfants des leaders n\u2019\u00e9tudient pas ici, ceux qui parlent pour les autres font ce que j\u2019ai mentionn\u00e9 ci- dessus et envoient leurs enfants \u00e9tudier \u00e0 l\u2019\u00e9tranger. Lorsqu\u2019ils obtiennent leur dipl\u00f4me, ils les inscrivent dans de bonnes \u00e9coles avec des syst\u00e8mes internationaux et ce secteur \u00e9ducatif ne les concerne pas car leurs enfants n\u2019y sont pas form\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais les dirigeants, laissez-moi vous dire que c\u2019est une mauvaise habitude de ne pas aimer votre patrie, c\u2019est une mauvaise habitude de ne pas aimer les citoyens et de savoir comment leur donner ce qu\u2019ils m\u00e9ritent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une autre chose que je voudrais vous dire sur l\u2019\u00e9ducation est que nos enfants vont passer 2 ans \u00e0 la maison. Depuis l\u2019\u00e9pid\u00e9mie de coronavirus, la premi\u00e8re action a \u00e9t\u00e9 la fermeture des \u00e9coles. Une ann\u00e9e enti\u00e8re s\u2019est \u00e9coul\u00e9e, les enfants du pays \u00e9tant \u00e0 la maison, tandis que d\u2019autres enfants qui sont dans les syst\u00e8mes internationaux \u00e9tudient et avancent dans les classes sans difficult\u00e9. Mais les enfants qui sont dans le syst\u00e8me rwandais, r\u00e9cemment, nous \u00e9tions fiers de l\u2019ouverture de l\u2019\u00e9cole, mais dans moins de deux mois, l\u2019\u00e9cole a ferm\u00e9. R\u00e9cemment, il y a eu une annonce aux parents pour se pr\u00e9parer \u00e0 l\u2019ouverture des \u00e9coles le 18, ceux de l\u2019\u00e9cole primaire qui n\u2019avaient pas encore commenc\u00e9, les parents se sont pr\u00e9par\u00e9s et ont vendu tout ce qu\u2019ils avaient, d\u2019autres ont emprunt\u00e9 de l\u2019argent et sont all\u00e9s payer les frais de scolarit\u00e9, les uniformes scolaires, ils sont all\u00e9s acheter du mat\u00e9riel scolaire, et la date de la reprise de l\u2019\u00e9cole qui \u00e9tait le 18, \u00e0 la m\u00eame date le 18 janvier, c\u2019est \u00e0 ce moment-l\u00e0 qu\u2019ils ont annonc\u00e9 la fermeture de toutes les \u00e9coles m\u00eame celles qui fonctionnaient. Pouvez-vous imaginer \u00e0 quel point cela a bless\u00e9 un parent qui avait fait toutes ces d\u00e9penses pour un enfant mais qui est maintenant assis \u00e0 la maison avec l\u2019enfant! Dirigeants, vous devriez r\u00e9fl\u00e9chir \u00e0 la souffrance des parents qui restent \u00e0 la maison pendant deux ans avec des enfants, pensez-vous aux cons\u00e9quences futures sur ces enfants ou sur ceux qu\u2019ils ont d\u00e9j\u00e0 subis?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ann\u00e9e derni\u00e8re, il y a eu un tr\u00e8s grand nombre de filles qui avaient eu des grossesses non d\u00e9sir\u00e9es pendant la p\u00e9riode de confinement. Je ne sais pas si Mme Janet Kagame a d\u00e9j\u00e0 entendu parler de ces chiffres parce que j\u2019ai entendu dire que dans ses initiatives, elle a une institution pour d\u00e9fendre les filles, pour les aider \u00e0 avancer. Je la voyais s\u2019occuper de tels travaux si je ne me trompe pas . Mais ce ne sont pas des choses que vous faites de mani\u00e8re formelle et que vous montrez aux Nations que vous pr\u00e9conisez pour les filles, y a-t-il quelque chose que vous avez pr\u00e9par\u00e9 pour ces filles Mme Janet Kagame? Je vous parle personnellement, je ne sais pas si vous nous ferez un retour, mais m\u00eame s\u2019il n\u2019y aurait pas , j\u2019aimerais que vous y r\u00e9fl\u00e9chissiez, et j\u2019esp\u00e8re que vous ferez quelque chose pour elles, car, maintenant ce qui a suivi c\u2019est que vous les avez ramen\u00e9s \u00e0 la maison, et m\u00eame ceux qui n\u2019avaient pas accouch\u00e9 vont probablement accoucher ou m\u00eame ceux qui avaient accouch\u00e9 vont retomber enceintes, et cela parce que les enfants rwandais n\u2019\u00e9tudient pas. Des enfants qui ont d\u00e9j\u00e0 acquis l\u2019habitude de travailler pour de l\u2019argent, est-ce que ces enfants vont retourner \u00e0 l\u2019\u00e9cole, respecter l\u2019enseignant et suivre les cours de mani\u00e8re humble car vous savez qu\u2019\u00e9tudier est un d\u00e9fi et pas quelque chose \u00e0 prendre pour acquis? Veuillez penser \u00e0 cela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a des enfants en \u00e2ge de commencer l\u2019\u00e9cole maternelle qui sont \u00e0 la maison, il y en a d\u2019autres qui \u00e9taient \u00e0 l\u2019\u00e9cole maternelle qui sont maintenant \u00e0 la maison, et nous savons tous qu\u2019au Rwanda, le nombre d\u2019enfants surtout dans les \u00e9coles publiques augmente tr\u00e8s rapidement, qu\u2019est-ce que vous allez faire avec ces enfants? Allez-vous obliger certains enfants d\u2019\u00e2ge scolaire \u00e0 rester \u00e0 la maison, allez-vous les mettre dans les m\u00eames classes? Je ne sais vraiment pas comment vous allez g\u00e9rer cette situation, mais en tant que parents et Rwandaise qui aiment le Rwanda, nous souhaitons que vous nous expliquiez clairement comment vous envisagez de r\u00e9soudre ce probl\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd\u2019hui Kigali est dans le confinement, en provinces les \u00e9l\u00e8ves \u00e9tudient, comment vont-ils passer le test national? Allez-vous pr\u00e9parer un test national pour les provinces et un autre pour la ville de Kigali? Ou allez-vous laisser les enfants \u00e9tudier et terminer leurs \u00e9tudes et leur donner des certificats? Vous devez nous expliquer clairement comment vous allez g\u00e9rer cette situation sans utiliser l\u2019expression \u00abnous verrons comment la g\u00e9rer\u00bb car cette expression comporte beaucoup de choses, qui peuvent \u00eatre positives pour les parents, sans oublier qu\u2019elles pourraient m\u00eame \u00eatre n\u00e9gatives et avoir des cons\u00e9quences sur nos enfants. Expliquez-nous comment vous allez le g\u00e9rer. Ces enfants qui sont \u00e0 l\u2019\u00e9cole alors que d\u2019autres ne le sont pas, vont-ils passer les examens ensemble? Vont-ils avoir le m\u00eame programme ou il y aura un changement au Rwanda et nous aurons un programme provincial et un programme pour la ville de Kigali?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci, mais je demanderais \u00e0 nos dirigeants de nous aider \u00e0 comprendre ce d\u00e9fi li\u00e9 \u00e0 l\u2019\u00e9ducation, car l\u2019\u00e9ducation au Rwanda a \u00e9t\u00e9 comme un terrain de jeu, veuillez cesser de jouer sur l\u2019\u00e9ducation de nos jeunes, car vos enfants \u00e9tudient sans difficult\u00e9, veuillez patienter et aidez-nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Permettez-moi de terminer ici ce point de l\u2019\u00e9ducation, mais je ne peux pas conclure sans mentionner les enfants rwandais qui sont dans l\u2019 internat jusqu\u2019\u00e0 aujourd\u2019hui. Il y a des enfants qui sont all\u00e9s dans les provinces qui sont dans des internats et ils sont nombreux et il y a m\u00eame ceux qui sont dans des internats \u00e0 Kigali. Chers Rwandais, ces enfants ont \u00e9t\u00e9 comme ceux qui ont commis des crimes, ils sont comme ceux qui sont en prison et ils ont \u00e9t\u00e9 s\u00e9par\u00e9s de leurs parents. Dirigeants, vous avez oubli\u00e9 les droits de la famille, vous avez oubli\u00e9 que les enfants ont besoin de conna\u00eetre les nouvelles de leurs familles, vous avez ignor\u00e9 que les parents ont besoin de conna\u00eetre les nouvelles de leurs enfants, imaginez par exemple si nous vous prenons Ministre ou Janet, mettez-vous \u00e0 la place des parents qui ont des enfants en internat. Si vous deviez \u00eatre emmen\u00e9 et s\u00e9par\u00e9 de vos enfants, s\u2019ils ont \u00e9t\u00e9 plac\u00e9s dans un internat et que vous n\u2019\u00eates pas autoris\u00e9 \u00e0 aller leur rendre visite, vous ne savez pas comment votre enfant a \u00e9t\u00e9, et quand vous demandez, ils vous disent que votre l\u2019enfant est l\u00e0, seulement \u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le m\u00eame point que nous avons abord\u00e9, celui de nous garder \u00e0 la maison et de porter des masques l\u00e0 o\u00f9 ce n\u2019est pas n\u00e9cessaire, nous pourrions ajouter un autre probl\u00e8me, celui du vaccin. Il existe actuellement un vaccin qui existe d\u00e9j\u00e0 dans notre pays, de telle sorte que certaines personnes sont d\u00e9j\u00e0 venues se faire vacciner. Il s\u2019agit notamment du personnel m\u00e9dical, des personnes \u00e2g\u00e9es et des personnes souffrant de maladies chroniques. Nous ne nous opposons pas au vaccin, je ne viens m\u00eame pas ici pour vous interdire d\u2019accepter la d\u00e9cision parce que la maladie est l\u00e0, je l\u2019accepte, mais il y a quelque chose \u00e0 quoi nous devons faire attention. Les vaccins dans la vie ordinaire ont une p\u00e9riode de test suffisante pour qu\u2019ils n\u2019aient pas de cons\u00e9quences sur ceux qui vont les utiliser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesdames et Messieurs, ce n\u2019est que moins d\u2019un an que ces vaccins contre le coronavirus ont \u00e9t\u00e9 fabriqu\u00e9s et test\u00e9s si l\u2019on consid\u00e8re l\u2019heure \u00e0 laquelle le coronavirus a \u00e9clat\u00e9. Ensuite, \u00eatre envoy\u00e9 dans notre pays et mis en \u0153uvre automatiquement, je pense que c\u2019est effrayant pour tout Rwandais r\u00e9fl\u00e9chi, car, m\u00eame ceux qui nous l\u2019ont envoy\u00e9, c\u2019est comme s\u2019ils ne lui faisaient pas confiance, ils ne croient pas en la fa\u00e7on dont cela fonctionne, ils ne connaissent pas ses cons\u00e9quences.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un autre aspect qui fait peur c\u2019est la fa\u00e7on dont cela se fait si rapidement. Depuis longtemps, il y a eu des maladies comme le diab\u00e8te, le sida, le cancer, ils n\u2019ont jamais cherch\u00e9 un vaccin de mani\u00e8re urgente, mais le vaccin contre le coronavirus se trouve en moins d\u2019un an. Nous devons \u00eatre tr\u00e8s prudents avec cela parce que les corps des Rwandais ne doivent pas \u00eatre des organismes de test pour affirmer l\u2019efficacit\u00e9 des vaccins. Ce ne sont pas des corps de vers ou de rats pour des tests de vaccin contre le coronavirus. Nous ne refusons pas le vaccin, mais le gouvernement devrait l\u2019aborder lentement et ne pas simplement commencer \u00e0 l\u2019appliquer sur la vie des gens. Chaque personne qui sera vaccin\u00e9e qu\u2019elle le fasse volontairement ou non, laisse-moi esp\u00e9rer que ce vaccin ne sera jamais obligatoire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La premi\u00e8re erreur de faire du vaccin une urgente a \u00e9t\u00e9 commise, mais j\u2019esp\u00e8re qu\u2019elle ne sera jamais obligatoire ici au Rwanda. Parfois, nous pouvons dire que ce n\u2019est pas une obligation alors que c\u2019est d\u2019une mani\u00e8re qui n\u2019est pas clairement visible. Cela peut \u00eatre indirectement obligatoire, par exemple, si c\u2019est dans un lieu de travail donn\u00e9, ils d\u00e9clarent que chaque personne qui s\u2019y rend doit \u00eatre vaccin\u00e9e. Et la personne qui est l\u00e0, au lieu de prendre le temps de l\u2019examiner et d\u2019y r\u00e9fl\u00e9chir, elle leur dit simplement qu\u2019elle n\u2019est pas autoris\u00e9e \u00e0 \u00eatre l\u00e0 parce qu\u2019elle peut contaminer les autres avec le coronavirus. De cette mani\u00e8re, il y aura une injustice pour les Rwandais, les vaccins auront \u00e9t\u00e9 rendus obligatoires d\u2019une mani\u00e8re qui n\u2019est pas visible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si quelqu\u2019un peut aller demander un service donn\u00e9 que ce soit dans une banque ou \u00e0 l\u2019h\u00f4pital et qu\u2019on lui dise qu\u2019il ne peut pas entrer sans montrer un document requis donn\u00e9, ou que vous ne pouvez pas prendre un taxi sans montrer un certificat attestant que vous avez \u00e9t\u00e9 vaccin\u00e9 contre le coronavirus , de cette fa\u00e7on nous aurons rendu indirectement le vaccin une obligation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est pourquoi j\u2019appelle mes compatriotes rwandais \u00e0 \u00eatre patients, aux dirigeants pour s\u2019assurer que ce vaccin n\u2019est pas obligatoire. Nous ne le savons pas encore, parfois, m\u00eame les pharmaciens qui les fabriquent se concentrent uniquement sur les gains d\u2019argent et ils oublient qu\u2019il s\u2019agit de prot\u00e9ger la vie humaine, surtout qu\u2019ils ne se soucient g\u00e9n\u00e9ralement pas des Africains. Ensuite, les dirigeants devraient nous pardonner et bien l\u2019organiser de mani\u00e8re \u00e0 ce que quiconque ressent de la peur et a besoin d\u2019\u00eatre vaccin\u00e9 puisse y aller de son propre chef, mais pour quelqu\u2019un qui y r\u00e9fl\u00e9chit encore, s\u2019il vous pla\u00eet, ne nous y obligez pas pour que demain nous commen\u00e7ons \u00e0 voir des gens nous venir \u00e0 la maison nous vacciner comme si c\u2019\u00e9tait la seule maladie qui n\u2019ait jamais exist\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jusqu\u2019\u00e0 pr\u00e9sent, j\u2019ai une question, je ne sais pas si d\u2019autres Rwandais l\u2019ont, je me demande s\u2019il n\u2019y a pas d\u2019autres maladies qui tuent car maintenant chaque personne qui souffre et meurt on dit qu\u2019ils sont tu\u00e9s par le coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019autres maladies sont-ils en vacances pour que, m\u00eame ceux qui ont souffert de diverses maladies comme le diab\u00e8te et d\u2019autres deviennent des d\u00e9c\u00e8s par coronavirus? Aucune autre personne n\u2019est tu\u00e9e par d\u2019autres maladies! Je ne sais pas si vous vous posez de telles questions! J\u2019y pense et je me rends compte qu\u2019il y a de nombreuses raisons qui peuvent pousser les gens \u00e0 prendre ce vaccin qui leur causera des probl\u00e8mes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je sais qu\u2019il y a eu un temps o\u00f9 notre pr\u00e9sident a dit qu\u2019il n\u2019avait plus besoin que les Blancs nous apportent ce qu\u2019ils veulent et nous dirigent comme ils le veulent. Cette fois, il agissait comme un Africain qui aime l\u2019Afrique, qui ne veut pas \u00eatre un canard de blancs. Pourquoi devenons-nous leurs canards aujourd\u2019hui en restant \u00e0 la maison, en portant des masques, pourquoi les copions-nous sans m\u00eame savoir dans quoi nous sommes, pourquoi devenons-nous leurs canards en prenant un vaccin fabriqu\u00e9 dans leur pays sans \u00eatre test\u00e9 par aucun Africain, ignorant que toutes les mati\u00e8res premi\u00e8res qu\u2019ils utilisent sont originaires d\u2019Afrique. La seule raison pour laquelle ils s\u2019int\u00e9ressent \u00e0 nous, c\u2019est leurs int\u00e9r\u00eats? Pourquoi fabriquent-ils un vaccin et en tr\u00e8s peu de temps, ils nous l\u2019envoient tr\u00e8s rapidement. Je demande au gouvernement d\u2019\u00eatre tr\u00e8s prudent \u00e0 ce stade et d\u2019\u00e9viter de nous le donner comme une obligation, et cette question du vaccin qui fait vraiment peur \u00e0 beaucoup de gens, je demande au gouvernement de prendre les devants et de nous aider de telle fa\u00e7on que seuls, ceux qui ont envie d\u2019\u00eatre vaccin\u00e9s le fassent et ceux qui ne veulent pas \u00eatre vaccin\u00e9s s\u2019en abstiennent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est tr\u00e8s important que nous consid\u00e9rions les questions pertinentes et que nous y travaillions s\u00e9rieusement et que nous surmontions et osions dire quelque chose, chers Rwandais. Permettez-moi de vous dire, qu\u2019il est temps que nous, les Rwandais, surmontions la peur et sachions ce que nous devons faire qui a un avantage pour nous et lib\u00e9rer la force de la majorit\u00e9. Si David devait continuer \u00e0 craindre Goliath, jusqu\u2019\u00e0 aujourd\u2019hui, les Philistins auraient toujours pers\u00e9cut\u00e9 le peuple de Dieu. Mais qu\u2019a-t-il utilis\u00e9 pour le tuer? Il n\u2019a utilis\u00e9 qu\u2019une pierre parce qu\u2019il savait qu\u2019il \u00e9tait soutenu par Dieu. Il est vrai que Dieu prend soin de nous. Mais nous aussi, nous devons nous lever et Lui demander des choses : demander la paix, demander la fiert\u00e9, personne n\u2019est autoris\u00e9 \u00e0 vous emp\u00eacher d\u2019\u00eatre fier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parfois, quand je regarde autour de moi, c\u2019est comme si nous pleurions des choses que nous ne connaissons pas ici au Rwanda. Je ne vois pas pourquoi nous ne sommes pas fiers, c\u2019est notre droit. Nous avons \u00e9t\u00e9 cr\u00e9\u00e9s pour \u00eatre fiers, mais \u00eatre fiers est un probl\u00e8me ici au Rwanda. Ce n\u2019est pas vrai. Soyons fiers, profitons de la vie, luttons contre le coronavirus, sans toutefois le laisser prendre le dessus pour nous cacher dans des trous, de telle mani\u00e8re que nous vivions en fuyant et nous tournions vers des endroits m\u00eame dangereux. Merci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019\u00e9tais sur la question des enfants dans les internats. Ces enfants sont comme des prisonniers avec des \u00e9coles. C\u2019est tr\u00e8s triste qu\u2019un parent appelle \u00e0 l\u2019\u00e9cole pour s\u2019enqu\u00e9rir de la sant\u00e9 d\u2019un enfant et il demande comment va l\u2019enfant et on lui dit que l\u2019enfant va bien et leur demande de lui donner une conf\u00e9rence et ils leur disent simplement que l\u2019enfant va bien et le parent pourrait \u00eatre inform\u00e9 de tout ce qui arrivera \u00e0 l\u2019enfant. Parents, Rwandais, que signifie ce mot pour un parent? Pouvez-vous vous endormir la nuit en entendant ce mot? Est-ce une garantie que votre enfant va bien? Il faut que chacun soit mis \u00e0 sa place. Je n\u2019affirme pas bien que parmi ces d\u00e9cideurs, si de telles d\u00e9cisions devaient \u00eatre prises sur leurs enfants, ils l\u2019accepteraient ou en seraient fiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Terminons ce point par ici, mais de toute fa\u00e7on, ils verront comment nous l\u2019expliquer avec les questions d\u2019\u00e9ducation, mais si un enfant est all\u00e9 au pensionnat, chers dirigeants, merci de bien vouloir nous pardonner ainsi que ces internats qui sont devenus des prisons pour enfants. , des internats devenus des objets de s\u00e9paration entre enfants et parents, c\u2019est tr\u00e8s triste, m\u00eame si vous voyez que les Rwandais ne parlent pas, restez simplement silencieux, c\u2019est tr\u00e8s embarrassant et il faut y r\u00e9fl\u00e9chir avec prudence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Passons rapidement au troisi\u00e8me point qui concerne le droit \u00e0 la libert\u00e9 de religion au Rwanda. Peut-\u00eatre pourriez-vous me demander de quelle foi je parle, mais partout dans le monde, chaque personne a sa propre fa\u00e7on d\u2019exposer sa foi. Il y a ceux qui prient, il y en a d\u2019autres qui pratiquent encore les cultes traditionnels, il y a ceux qui croient au Christ, il y a ceux qui croient en Mohamed, mais en tant que Rwandais, nous devons avoir la libert\u00e9 de notre foi. La raison pour laquelle j\u2019ai pens\u00e9 \u00e0 cela, ce n\u2019est pas un point sur lequel je vais m\u2019attarder parce que je ne suis pas pasteur, je ne suis pas religieux et je dois parler en tant que repr\u00e9sentant des religions, mais j\u2019ai vu que lors du premier confinement, les premiers endroits \u00e0 \u00eatre ferm\u00e9s \u00e9taient les \u00e9glises. Je ne vois pas pourquoi les \u00e9glises devaient \u00eatre ferm\u00e9es en premier lieu. Je ne vois pas comment les gens peuvent aller au march\u00e9, se contr\u00f4ler, respecter les mesures de distanciation sociale, se laver les mains et porter des masques, mais cependant, ceux qui vont aux \u00e9glises ne peuvent pas le faire. Je me demande si ces gens qui vont \u00e0 l\u2019\u00e9glise sont t\u00eatus de telle mani\u00e8re qu\u2019ils ne peuvent pas faire ce que font ceux qui vont au march\u00e9, c\u2019est \u00e0 dire respecter la distance sociale, se laver les mains, porter des masques et adorer Dieu. Respecter la foi de chacun, les laisser aller dans la maison de Dieu et prier, surtout que, j\u2019ai \u00e9tudi\u00e9 que la religion ou l\u2019ob\u00e9issance \u00e0 Dieu fait partie des toutes premi\u00e8res choses qui aident le gouvernement \u00e0 bien diriger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parce qu\u2019il y a des choses que les citoyens ne font pas, pas parce qu\u2019ils craignent le gouvernement, mais parce qu\u2019ils craignent Dieu, gr\u00e2ce \u00e0 leur foi. Il pourrait y avoir quelqu\u2019un qui ne craindrait pas de tuer une personne parce qu\u2019il dit qu\u2019il la mettrait en prison, mais s\u2019il se tournait vers la foi, craignez Dieu parce qu\u2019il sait que tuer est un p\u00e9ch\u00e9. Alors je me demande comment le gouvernement ferra r\u00e9gner l\u2019ordre s\u2019il n\u2019y a pas d\u2019ob\u00e9issance \u00e0 Dieu dans le pays! Si l\u2019ob\u00e9issance \u00e0 Dieu tend \u00e0 se perdre dans le pays, n\u2019est-ce pas une question qui causera des troubles au pays \u00e0 l\u2019avenir, de m\u00eame que la question de l\u2019\u00e9ducation?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a une fa\u00e7on dont j\u2019ai pens\u00e9 \u00e0 ce probl\u00e8me : Imaginez si vous \u00e9tiez un homme et que quelqu\u2019un vous chassait de votre maison et que vous en souffriez beaucoup. Lorsque la pand\u00e9mie a \u00e9clat\u00e9 pour la premi\u00e8re fois dans le pays, le fait que la premi\u00e8re chose \u00e0 faire a \u00e9t\u00e9 de chasser Dieu du pays, a \u00e9t\u00e9 quelque chose qui ne pouvait pas \u00eatre expliqu\u00e9. D\u2019autres lieux s\u2019ouvraient progressivement, ce qui \u00e9tait tr\u00e8s lent et rare pour les \u00e9glises et avec de nombreuses conditions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est vrai qu\u2019on nous apprenait \u00e0 lutter contre le coronavirus dans la maison de Dieu, mais ce coronavirus pour nous faire perdre la t\u00eate, le coronavirus pour nous faire parler de n\u2019importe quoi. Parfois j\u2019analyse, laissez-moi le dire je n\u2019ai pas peur de le dire, parce que je l\u2019ai dit, il y a des niveaux que vous atteignez et vous n\u2019avez plus peur. Je vois que le coronavirus est devenu un jeu ici au Rwanda. Regardez-le tr\u00e8s bien, je me rends parfois compte que le coronavirus est devenu un jeu au Rwanda, oui il est l\u00e0, et la fa\u00e7on dont nous le prenons n\u2019est pas la fa\u00e7on dont il devrait \u00eatre pris. Nous lui accordons beaucoup de poids pour des raisons politiques, je n\u2019ai pas peur de le dire. Nous accordons au coronavirus beaucoup plus de poids qu\u2019il n\u2019en a et prenons des mesures au-del\u00e0 de ce que nous devrions prendre, en raison des int\u00e9r\u00eats sp\u00e9cifiques du gouvernement. Je ne comprends pas comment nous d\u00e9cidons que les gens restent chez eux, alors que les a\u00e9roports sont ouverts, que les touristes viennent visiter la beaut\u00e9 du Rwanda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un \u00e9tranger peut venir frapper \u00e0 votre porte ayant \u00e9t\u00e9 autoris\u00e9 \u00e0 entrer par le pays sous pr\u00e9texte qu\u2019il a \u00e9t\u00e9 test\u00e9 pour le coronavirus, alors que votre voisin n\u2019a pas le droit de venir vous demander comment vous avez pass\u00e9 votre nuit, m\u00eame ceux dont les parents meurent les provinces ne peuvent pas aller les enterrer sans avoir une autorisation sp\u00e9cifique. Si votre ami peut mourir sans les voir alors que vous n\u2019\u00eates pas des ennemis, et qu\u2019un \u00e9tranger a le droit dans votre pays plus que vous. Essayez de le voir, m\u00eame lorsque vous vous rencontrez \u00e0 la banque, ils font passer un \u00e9tranger pendant que vous restez dans la file d\u2019attente. Pourquoi \u00e7a? Pourquoi ont-ils plus de droits dans notre pays que nous? Je vous ai dit que nous ne sommes plus sous une colonisation que nous avons d\u00e9j\u00e0 surmont\u00e9e. S\u2019il vous pla\u00eet, ne nous ramenez pas \u00e0 la colonisation. Ensuite, quand vous le regardez, vous vous rendez compte que le coronavirus est une carte de jeu du gouvernement qu\u2019il utilise pour prot\u00e9ger ses int\u00e9r\u00eats, sous-estimant les int\u00e9r\u00eats de la population qui constitue la majorit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez \u00eatre patients rwandais nos dirigeants, ne nous posez pas de probl\u00e8me d\u2019\u00eatre beaucoup plus intelligents que nous, de nous prendre pour des objets, de nous jouer aux cartes, comme si nous n\u2019\u00e9tions pas intelligents et juste faire les choses pour vos propres int\u00e9r\u00eats. Le coronavirus est une carte de jeu, une carte de jeu de g\u00e9nocide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au Rwanda, il y a quelques temps, quand nous \u00e9tions encore enfants, quelqu\u2019un pouvait faire quelque chose et ensuite juste pour les humilier, on pouvait les bl\u00e2mer comme s\u2019ils avaient commis un g\u00e9nocide. Chers Rwandais, ne g\u00e9n\u00e9ralisons pas et ne consid\u00e9rons pas toutes les personnes comme des malfaiteurs, sans oublier qu\u2019il y a ceux qui nous ont cach\u00e9s et jusqu\u2019\u00e0 pr\u00e9sent nous sommes encore en vie gr\u00e2ce \u00e0 eux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque fois que la carte du jeu du g\u00e9nocide, chaque fois que le g\u00e9nocide contre les Tutsi est devenu une chanson, des monuments sont visit\u00e9s, des devises \u00e9trang\u00e8res circulent dans le pays pour le g\u00e9nocide contre les Tutsi, nos corps sont vendus, je n\u2019ai pas peur de le dire, et nous, les survivants, sommes comme sous-estim\u00e9s, ne recevant aucun soin de personne, oui, FARG (une organisation qui assiste des survivants du g\u00e9nocide au Rwanda) s\u2019est occup\u00e9 de nous, mais comment pouvez-vous en tant que parent prendre soin d\u2019un enfant et qu\u2019ils n\u2019ont pas de v\u00eatements \u00e0 porter? Comment pouvez-vous payer l\u2019\u00e9cole pour un enfant qui n\u2019a pas de frais de transport pour y aller et comment y arrivera-t-il? Et quand ils ont fini, ils s\u2019assoient et disent que les enfants de FARG ne sont pas s\u00e9rieux, ce sont eux qui ne sont pas intelligents parce qu\u2019ils \u00e9tudient gratuitement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019entendais tout \u00e7a, j\u2019\u00e9tais frustr\u00e9 et je ne savais pas quoi faire. Nous \u00e9tions plut\u00f4t ceux qui \u00e9taient intelligents. Prenez votre propre enfant et emmenez-le \u00e9tudier dans les conditions dans lesquelles nous nous trouvions, sans personne pour prendre soin d\u2019eux, personne pour les aider et voir s\u2019ils pourront \u00e9tudier. Nous \u00e9tions tr\u00e8s intelligents. Et vous consommez beaucoup \u00e0 cause de cette carte de jeu. Nous \u00e9coutons tout \u00e7a mais nous souffrons en silence. Il y a des veufs dont les maisons s\u2019effondrent sur eux, ceux dont les maisons avaient \u00e9t\u00e9 construites dans des mat\u00e9riaux fragiles puis se sont effondr\u00e9s. Mais les corps de nos proches sont vendus dans diff\u00e9rents m\u00e9moriaux du g\u00e9nocide, et vous passez du temps \u00e0 chanter le g\u00e9nocide comme c\u2019est facile chanter quelque chose qui ne vous est pas arriv\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9sol\u00e9, ce n\u2019est pas \u00e7a sur quoi je voulais me concentrer; c\u2019est que parfois, j\u2019ai beaucoup des choses dans le c\u0153ur et elles d\u00e9bordent. Je vois que le coronavirus va \u00eatre une carte de jeu comme le g\u00e9nocide au Rwanda. Arr\u00eatons-nous. \u00c0 chaque fois qu\u2019il s\u2019agit d\u2019un coronavirus, les gens ont peur \u00e0 cause du coronavirus. Mais comment une personne porte-t-elle un masque, debout devant son enceinte? Je ne suis pas venu pour emp\u00eacher les Rwandais de lutter contre le coronavirus. Je suis d\u2019accord avec le port d\u2019un masque, mais sans oublier que l\u2019oxyg\u00e8ne que nous respirons vers l\u2019ext\u00e9rieur est mauvais et que nous ne devons donc pas le respirer vers l\u2019int\u00e9rieur. Nous souffrirons beaucoup plus du coronavirus parce que nous respirons l\u2019oxyg\u00e8ne des masques. Nous devons respirer un bon air, de l\u2019oxyg\u00e8ne de l\u2019ext\u00e9rieur. C\u2019est ainsi que Dieu a cr\u00e9\u00e9 l\u2019\u00eatre humain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il se peut que nous les portions peut-\u00eatre au march\u00e9, ailleurs o\u00f9 il y a beaucoup de monde, mais sans forc\u00e9ment avoir \u00e0 ab\u00eemer notre corps. Mais, m\u00eame debout devant son enceinte, il faut forc\u00e9ment mettre un masque? Si vous \u00eates seul, que devez-vous couvrir? Les gens qui sont dans la m\u00eame voiture de la m\u00eame maison, et une police<br>les arr\u00eate et leur demande pourquoi les masques sont baiss\u00e9s. Ils sont de la m\u00eame maison, ils restent dans la m\u00eame maison, s\u2019il vous pla\u00eet, soyez raisonables et donnez la paix aux Rwandais, pour qu\u2019ils aient le temps de se d\u00e9tendre et d\u2019\u00eatre fiers. Les Rwandais ne profitent plus de la vie. Soyez patient et arr\u00eatez tr\u00e8s souvent d\u2019utiliser le coronavirus pour que cela devienne un autre pr\u00e9texte pour les Rwandais d\u2019\u00eatre moralement bless\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On d\u00e9cide de rester \u00e0 la maison, aller travailler \u00e0 l\u2019ext\u00e9rieur est tr\u00e8s probl\u00e9matique, pour sortir, il faut s\u2019expliquer, mais l\u2019\u00e9quipe nationale peut aller jouer \u00e0 l\u2019\u00e9tranger. Ne sont-ils pas des Rwandais? Les d\u00e9testons-nous? Pourquoi g\u00e2tons-nous leur corps et leur permettons-nous d\u2019aller jouer dans de tels moments? Il y a eu r\u00e9cemment une question apr\u00e8s la victoire de notre \u00e9quipe, si c\u2019\u00e9tait une question ou une r\u00e9ponse je ne sais pas comment l\u2019expliquer, mais pour les rwandais c\u2019\u00e9tait une r\u00e9ponse car c\u2019\u00e9tait une victoire, le probl\u00e8me \u00e9tait qu\u2019il y avait du monde qui ont \u00e9t\u00e9 ravis et ont exprim\u00e9 leur joie dans les rues. Ils ont m\u00eame oubli\u00e9 les masques, sont devenus fous et sont all\u00e9s chanter la victoire de l\u2019\u00e9quipe nationale. Mais dans notre nature de Rwandais, nous avons \u00e9t\u00e9 cr\u00e9\u00e9s un peuple heureux, c\u2019est ainsi qu\u2019un \u00eatre humain est m\u00eame partout dans le monde. Parce qu\u2019il est vrai que c\u2019est un enjeu cl\u00e9 pour quelqu\u2019un de vivre plus longtemps, mais que les structures polici\u00e8res vont prendre des mesures, je crois que le jour o\u00f9 l\u2019\u00e9quipe nationale jouera, il y aura des agents de police sur chaque terrain pour que personne ne sorte . Mais nous croyons que c\u2019est notre \u00e9quipe nationale et que nous sommes des citoyens. Par cons\u00e9quent, prendre des mesures pour rester \u00e0 la maison devrait \u00eatre pour tout le monde sans exception s\u2019il n\u2019y a pas de sp\u00e9culation \u00e0 ce sujet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u2019il n\u2019y a pas de sp\u00e9culation sur les devises \u00e9trang\u00e8res \u00e0 entrer, les touristes ne viendraient pas dans le pays, ceux qui apportent ce coronavirus, ils auraient d\u00fb \u00eatre arr\u00eat\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce que je ne sais pas, c\u2019est la raison pour laquelle nous restons \u00e0 la maison, mais le nombre de ceux qui sont test\u00e9s positifs ne cesse d\u2019augmenter! Comment est-ce possible? Le gouvernement devrait essayer d\u2019\u00eatre notre \u0153il, et comme je le vois, il est temps que chacun qui croit avoir ce qu\u2019il peut faire pour les Rwandais pour qu\u2019ils aient la paix le fasse, en fonction de leur pouvoir. Je dis cela, mais je sais qu\u2019il y en a encore beaucoup plus qui y pensent, et qui peuvent faire quelque chose \u00e0 ce sujet, nous leur demandons de se lever et de faire quelque chose pour que les Rwandais obtiennent la paix, pour que nous vivions nos vies ordinaires car il est n\u00e9cessaire. Laissez-moi conclu ce point sur la libert\u00e9 religieuse, qui m\u2019a d\u2019ailleurs pris un peu plus de temps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je vais aborder un autre point, le quatri\u00e8me point : Je me demande si les Rwandais ne sont pas comme des moutons sans berger! Un berger signifie un esclave, un chef, quelqu\u2019un qui voit pour les autres, c\u2019est ce que je veux dire par berger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La raison pour laquelle je me demande si les Rwandais ne sont pas comme des moutons sans berger, c\u2019est parce que toutes ces choses que nous traversons, ces choses qui nous embarrassent, il y a un moyen de s\u2019en d\u00e9barrasser, car il y en a qui sont charg\u00e9 de cela, ils pourraient s\u2019occuper de cela en notre nom. Dans la vie normale, quand il y a un probl\u00e8me, le p\u00e8re de la maison est celui qui sort, s\u2019il y a une question effrayante, c\u2019est le p\u00e8re de la maison qui sort, c\u2019est pourquoi la Bible l\u2019appelle le chef de la maison. Il sort pour voir ce qui se passe, de sorte qu\u2019au besoin il calme les autres membres de la famille, car il a plus de pouvoir et d\u2019autorit\u00e9 qu\u2019eux. Si le mari n\u2019est pas l\u00e0, est malade ou a un autre probl\u00e8me, c\u2019est la femme qui sort. Elle sort \u00e0 la place du repr\u00e9sentant de la maison et revient calmer les enfants. Ils ne peuvent pas continuer \u00e0 pleurer tant qu\u2019il y a des parents. Et quand les parents ne sont pas l\u00e0, il y a g\u00e9n\u00e9ralement d\u2019autres personnes qui vivent dans cette enceinte, par exemple des agents de s\u00e9curit\u00e9 ou d\u2019autres employ\u00e9s, qui sortent et reviennent pour calmer les enfants sur l\u2019absence de danger. Quand toutes ces personnes ne sont pas l\u00e0 et que le p\u00e8re de famille a des enfants plus \u00e2g\u00e9s, l\u2019a\u00een\u00e9 ou l\u2019a\u00een\u00e9 apr\u00e8s lui \/ elle, est celui qui sort pour voir ce qui se passe et revient voir les petits fr\u00e8res \/ s\u0153urs et leur dit : calmez-vous, il n\u2019y a pas de danger et sait comment g\u00e9rer la situation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par cons\u00e9quent, ce que j\u2019ai vu au Rwanda est \u00e9trange. Je ne peux pas dire que c\u2019est \u00e9trange d\u2019une mani\u00e8re sacr\u00e9e, c\u2019est vraiment \u00e9trange d\u2019une mani\u00e8re que je ne peux pas qualifier. J\u2019ai vu qu\u2019au Rwanda, chacun se bat pour lui-m\u00eame, en sa propre capacit\u00e9, dans ce qu\u2019il ne peut pas se permettre et que les gens se taisent. Mais, mes chers, depuis que la pand\u00e9mie de coronavirus a \u00e9clat\u00e9, je n\u2019ai jamais vu Son Excellence le pr\u00e9sident de la R\u00e9publique sortir, prendre un micro et dire aux Rwandais: \u00abRwandais mon peuple, restez forts, n\u2019ayez pas peur, ne vous d\u00e9couragez pas, la pand\u00e9mie est l\u00e0, mais nous avons des strat\u00e9gies pour la combattre, et comme nous vous exhortons \u00e0 rester chez vous; entrez dans la maison, mais vous serez nourris de cette fa\u00e7on. Calmez- vous, aucun Rwandais ne mourra de faim, aucun Rwandais ne manquera de moyens de se faire soigner, calmez-vous, restez forts, je suis l\u00e0 en tant que votre chef, je suis devant vous. Je ne sais pas s\u2019il y en a d\u2019autres qui l\u2019ont vu, mais personnellement, honn\u00eatement, je ne l\u2019ai pas vu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce \u00e0 quoi je pensais, c\u2019\u00e9tait que, s\u2019il voyage et qu\u2019il n\u2019est pas l\u00e0, ou pour d\u2019autres raisons, Mme Janet Kagame devait prendre le micro, en tant que parent, surtout que, nous les parents nous sommes tr\u00e8s souvent \u00e9motifs, quand il y a un probl\u00e8me, tr\u00e8s souvent nous avons tendance \u00e0 courir et \u00e0 tenir les enfants ensemble pour les calmer. Je croyais qu\u2019elle aurait pris le micro et prendre les devants en tant que premi\u00e8re dame, et nous dire: \u00abcalmez-vous, soyez calme, m\u00eame s\u2019il n\u2019est pas l\u00e0, il y a des strat\u00e9gies que nous envisageons pour vous prot\u00e9ger. Il y a des strat\u00e9gies que le pays a d\u00e9j\u00e0 pens\u00e9 \u00e0 mettre en \u0153uvre, soyez calme, aucun Rwandais ne mourra de faim, m\u00eame si le coronavirus est l\u00e0, tenons-nous fermement et prions. Je n\u2019ai jamais vu quelque chose comme \u00e7a. \u00c0 vrai dire, je n\u2019ai jamais vu quelque chose comme \u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons des ministres, nous avons comme le Premier ministre et divers dirigeants, d\u00e9put\u00e9s et dirigeants que nous avons \u00e9lus, je n\u2019ai vu personne prendre un micro et nous parler, nous dire qu\u2019il faut \u00eatre calme car ils sont l\u00e0 devant nous, l\u00e0 sont des choses que nous sommes sur le point de faire, nous pr\u00e9parons ceci et cela, nous sommes sur le point de le faire, il n\u2019y a pas de probl\u00e8me, aucun Rwandais ne mourra de faim, et que nous lutterons contre le coronavirus en tant que Rwandais unis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai vu ce qui est similaire, mais ce n\u2019\u00e9tait pas r\u00e9el. Je ne l\u2019ai pas vraiment vu. Si toutes ces personnes ne sont pas l\u00e0, Son Excellence notre pr\u00e9sident a des enfants d\u2019\u00e2ge m\u00fbr. Ce qui plairait aux gens pendant la p\u00e9riode de s\u00e9jour \u00e0 la maison, ce serait d\u2019entendre par exemple qu\u2019Ange a pris de la nourriture, est all\u00e9 dans un village et a distribu\u00e9 la nourriture pour que les gens ne meurent pas de faim. Ce serait d\u2019entendre que cet enfant a pris un camion plein de riz ou de farine de ma\u00efs dans une zone donn\u00e9e, mais pas celui qui a p\u00e9ri, il \/ elle est all\u00e9e aider une zone donn\u00e9e afin que d\u2019autres enfants aient de quoi manger. Peut-\u00eatre, je ne sais pas si vous avez vu de telles choses, mais personnellement, je n\u2019ai jamais vu quelque chose comme \u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et ce qui nous ferait plaisir serait de les voir dans des moments difficiles, dans des moments o\u00f9 quelqu\u2019un peut passer une nuit vide et mourir dans sa maison, sans que son voisin ne soit pas au courant. C\u2019est ce que j\u2019ai vu qui serait agr\u00e9able. C\u2019est ce qui m\u2019a fait dire que les Rwandais souffrent de l\u2019int\u00e9rieur du c\u0153ur et chuchotent en parlant, les gens le disent et vous pouvez voir qu\u2019ils sont fatigu\u00e9s dans leur c\u0153ur, mais, dans ce que nous traversons, o\u00f9 sont nos dirigeants?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces gens qui voient pour nous, les g\u00e9n\u00e9raux, les officiers de l\u2019arm\u00e9e, o\u00f9 sont-ils? Ces personnes auxquelles vous avez pens\u00e9 et qui risquent de mourir de faim en continuant \u00e0 leur dire de rester \u00e0 la maison pour lutter contre le coronavirus, vous avez beaucoup de pouvoir pour faire quelque chose de mani\u00e8re \u00e0 ce que chaque Rwandais se d\u00e9tende, fasse quelque chose pour que les Rwandais obtiennent la paix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si je commence par vous James Kabarebe, vous \u00eates le conseiller du pr\u00e9sident, vous \u00eates le conseiller du pays, et vous gardez de nombreux secrets. Il y a m\u00eame des secrets qui jusqu\u2019\u00e0 pr\u00e9sent ne sont pas faciles pour vous. Vous gardez de nombreux secrets sensibles du pays et vous pouvez faire beaucoup de choses. Kabarebe vous avez la cl\u00e9 !! Vous avez la cl\u00e9 pour ramener les Rwandais en paix si vous le souhaitez, en ce moment, vous avez la cl\u00e9 pour faire quelque chose. Attendez-vous que Dieu Lui-m\u00eame vous dise de faire quelque chose pour que les Rwandais soient libres? Soyez patient et courageux! Soyez courageux au moins une fois dans la vie, lib\u00e9rez les Rwandais, essayez, et essayez au moins. Je vous en supplie, faites de votre mieux. Il y a vos tantes, vos neveux, les Rwandais sont tr\u00e8s tristes m\u00eame s\u2019ils vous montrent qu\u2019ils rient. Leur c\u0153ur est pourri. Je vous en prie, pardonnez-nous et ne nous faites pas comme l\u2019enfant qui vit chez leur belle-m\u00e8re, quand la belle-m\u00e8re voit le p\u00e8re, elle porte l\u2019enfant, les habille tr\u00e8s bien, les nourrit et danse pour eux. Mais quand le p\u00e8re est parti, les torture, les bat et les fait mourir de faim, parce qu\u2019elle a montr\u00e9 au p\u00e8re qu\u2019elle aime son enfant alors qu\u2019en r\u00e9alit\u00e9 elle ne les aime pas. C\u2019est ainsi que les Rwandais sont aux yeux des \u00e9trangers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous rencontrez des \u00e9trangers, vous leur montrez la beaut\u00e9 des Rwandais. Vous leur montrez que nous sommes en paix, que nous sommes d\u00e9velopp\u00e9s et qu\u2019il n\u2019y a pas de Rwandais qui meurt de faim, mais ce n\u2019est pas ainsi que les choses se passent, le c\u0153ur des Rwandais est pourri, ils sont tr\u00e8s tristes, leur c\u0153ur est bris\u00e9. S\u2019il vous pla\u00eet, faites quelque chose pour leur donner la paix, au moins, soyez courageux une fois. Mme Janet Kagame, vous pouvez faire quelque chose en tant que parent. Regardez les enfants du Rwanda et rappelez-vous que si vos enfants sont emp\u00each\u00e9s de sortir, vous souffrirez, si vous \u00eates emp\u00each\u00e9 de sortir, vous souffrirez, et vous et vos enfants \u00eates invit\u00e9s \u00e0 rester \u00e0 la maison pendant que vous n\u2019avez pas quoi \u00e0 donner pour manger. En tant que parent et m\u00e8re, imaginez quelqu\u2019un qui vous oblige \u00e0 rester \u00e0 la maison alors que vous n\u2019avez rien \u00e0 donner aux enfants! Comment te sentirais-tu? Il y a quelque chose \u00e0 faire!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Rwandais ne devraient pas continuer \u00e0 vivre comme des moutons sans berger, comme des gens sans chefs. Si vous prenez des d\u00e9cisions qui ont \u00e9t\u00e9 prises par les Europ\u00e9ens, mieux vaut aller en Europe et nous laisser notre Rwanda. Nous voulons rester avec notre d\u00e9mocratie. Si vous voulez que nous prenions des d\u00e9cisions comme celles prises par les blancs, nous le ferons pas parce que nous ne retournons pas sous leur colonisation. Il y a quelque chose que vous pouvez faire, il y a quelque chose que vous pouvez faire. Ne sous-estimez pas les gens ordinaires, vous ne verrez jamais un pays de riches seulement, il y aura dans le pays, des gens de toutes cat\u00e9gories, c\u2019est ainsi que Dieu l\u2019a pr\u00e9vu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il ne faut pas sous-estimer le droit \u00e0 la vie, le droit fondamental d\u2019un Rwandais. C\u2019est pourquoi je dis que nous ne pouvons pas continuer \u00e0 vivre comme des brebis sans berger. Essayez de prendre les devants pour nous, essayez de nous aider, soyez plus proches de nous et faites ce que nous attendons de vous. Je vous le demande s\u00e9rieusement. Je ne demande pas que le pr\u00e9sident sorte pour vous voir, ou accepte qu\u2019il soit l\u00e0, non, ce n\u2019est pas ce que je demande, laissez-le se reposer, laissez reposer notre vieil homme. En fait, chaque personne a son propre temps pour dialoguer avec Dieu. Et lorsque vous interagissez avec Dieu, vous n\u2019avez pas le droit de dire non. Non! Vous pouvez sous-estimer les gens, mais vous ne pouvez pas refuser quand Dieu dit qu\u2019il veut dialoguer avec vous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je ne veux pas entrer dans les d\u00e9tails \u00e0 ce sujet, pas du tout, ce que je demande seulement, c\u2019est que ceux qui ont le pouvoir de nous lib\u00e9rer le fassent, afin que demain nous n\u2019ayons pas de personnes qui se suicident \u00e0 cause du chagrin. M\u00eame si chaque personne qui dit ce qui est le contraire de ce que veut le gouvernement est prise comme ennemie du pays, je sais que dans la culture rwandaise, je sais qu\u2019en me levant pour le dire, vous pouvez m\u2019appeler ainsi mais ce n\u2019est pas vrai. Plut\u00f4t, si tous les Rwandais devaient se lever et aimer le pays, aimer les citoyens et dire qu\u2019ils ne veulent pas qu\u2019ils soient des sujets d\u2019injustice, ce serait un succ\u00e8s pour nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je ne suis pas un ennemi du pays, je suis une Rwandaise qui aime les Rwandais, qui est tr\u00e8s choqu\u00e9e par ce qui arrive aux Rwandais, les probl\u00e8mes auxquels ils sont confront\u00e9s, qui a un esprit patriotique d\u2019aimer les Rwandais o\u00f9 qu\u2019ils soient, que ce soit ici dans le pays ou dans la brousse, ou \u00e0 l\u2019\u00e9tranger ou ailleurs, mon c\u0153ur les aime \u00e0 condition qu\u2019ils soient rwandais et qu\u2019ils aient le m\u00eame droit que celui des autres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est pour \u00e7a que je me bats, je ne me bats pas pour des positions politiques, je suis d\u00e9sol\u00e9e de ne pas avoir besoin de \u00e7a, je ne viens m\u00eame d\u2019aucun parti politique, seulement je suis tr\u00e8s triste de voir que les Rwandais ne vivent pas comme ils devraient vivre , Je suis triste de voir qu\u2019ils n\u2019appr\u00e9cient pas la vie, c\u2019est pourquoi je m\u2019exprime. Je ne suis pas un ennemi du pays, je ne me bats pas contre mon pays. Si je me l\u00e8ve et que vous me traitez comme un ennemi, mais ce n\u2019est pas ainsi que les choses se passent. Seulement, je n\u2019ai pas peur au point que \u00e7a me domine, je ne me suicide m\u00eame pas, si vous \u00eates parent et m\u00e8re de quatre enfants, si vous mourez il y en a beaucoup qui souffrent, il y a m\u00eame ceux qui deviennent orphelins. J\u2019en ai peur parce que j\u2019ai grandi en \u00e9tant orpheline. J\u2019en ai alors peur, mais en avoir peur ne veut pas dire que je voulais forc\u00e9ment rester cach\u00e9 dans un coin et continuer \u00e0 me taire pendant que je vois d\u2019autres Rwandais victimes d\u2019injustice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je n\u2019ai pas r\u00e9ussi \u00e0 garder le silence avec \u00e7a, je veux que tu sois patient avec \u00e7a, et fais ce que tu veux, m\u00eame si tu veux, tu peux venir m\u2019arr\u00eater aujourd\u2019hui et m\u2019amener au tribunal pour m\u2019accuser de crimes, m\u00eame si tu ajoutes plus de crimes, je suis pr\u00eat \u00e0 passer par l\u00e0. \u00c0 ce moment-l\u00e0, m\u00eame si vous me tuez, mes r\u00eaves de vous faire savoir que les Rwandais sont tr\u00e8s tristes sont devenus r\u00e9alit\u00e9. M\u00eame si nous sourions, nous sommes tr\u00e8s malheureux. Je me bats pour rien d\u2019autre, mais pour les int\u00e9r\u00eats du peuple rwandais qui fait la majorit\u00e9, ces femmes avec un panier que vous courez toujours apr\u00e8s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il faut savoir que tous les Rwandais ont le m\u00eame droit. S\u2019il y a autre chose que j\u2019avais le pouvoir de faire, je pourrais le faire, je n\u2019ai pas d\u2019arme, je ne sais m\u00eame pas comment le tenir, je ne sais pas Je n\u2019ai pas non plus de gardes du corps, et je suis un citoyen tr\u00e8s ordinaire, je suis une personne qui ne peut pas \u00eatre tu\u00e9e au hasard comme on le voudrait parce que j\u2019ai un puissant roi sur moi, cette arme (la Bible) que j\u2019ai, peut se battre pour moi, si on veut me tuer alors que je ne me suis pas battu pour mon int\u00e9r\u00eat personnel, et me battre pour les int\u00e9r\u00eats des Rwandais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est temps de laisser libre le peuple de Dieu et ce sont des Rwandais, il est temps de laisser les Rwandais avoir le droit de vivre au Rwanda comme des Rwandais, de se d\u00e9tendre et d\u2019\u00eatre fiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est temps que les dirigeants lib\u00e8rent le peuple de Dieu et ce sont les Rwandais, permettez-moi de le r\u00e9p\u00e9ter pour vous, il est temps de lib\u00e9rer le peuple de Dieu, et ce sont les Rwandais. Laissez les Rwandais se d\u00e9tendre, laissez les Rwandais \u00eatre heureux, arr\u00eatez de les tuer de chagrin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et vous les Rwandais, il est temps que vous surmontiez la peur et d\u00e9montriez que vous \u00eates triste, et arr\u00eatez de pr\u00e9tendre que vous \u00eates heureux alors que vous ne l\u2019\u00eates pas. Laissez-moi vous dire quelque chose. Si Mo\u00efse devait rester au palais du roi comme c\u2019est l\u00e0 o\u00f9 il avait \u00e9t\u00e9 \u00e9lev\u00e9, manger de la nourriture et \u00eatre heureux, les Isra\u00e9lites ne se seraient pas d\u00e9barrass\u00e9s de l\u2019exploitation des \u00c9gyptiens. M\u00eame aujourd\u2019hui, ils seraient encore dans l\u2019exploitation \u00e9gyptienne. Mo\u00efse a d\u00fb surmonter la peur. Il est donc temps pour quiconque a quelque chose \u00e0 faire, de cesser de consid\u00e9rer qu\u2019il est \u00e0 l\u2019int\u00e9rieur du pays et d\u2019avoir peur qu\u2019on va l\u2019arr\u00eater.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non, je ne suis pas au Burundi notre pays voisin, comme je l\u2019ai dit, je suis dans la ville de Kigali, je vous ai dit o\u00f9 je suis \u00e0 Kimironko, dans le district de Gasabo. Laissez-moi vous dire mon num\u00e9ro de t\u00e9l\u00e9phone avant que j\u2019oublie pour que quiconque re\u00e7oit une question sur ma vid\u00e9o demande une explication de ma part, et m\u00eame quiconque voudrait m\u2019arr\u00eater soit pour m\u2019emmener en prison pour ne pas avoir \u00e0 enqu\u00eater de loin, juste qu\u2019ils m\u2019appellent et me disent que c\u2019est la police rwandaise. Je serai volontairement pr\u00e9sente. Je ne me cache pas, je vous ai dit que je m\u2019appelle Idamange Iryamugwiza Yvonne, mon num\u00e9ro de t\u00e9l\u00e9phone est le 0788830576, je le r\u00e9p\u00e8te, et c\u2019est le 0788830576.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Celui qui a besoin de moi peut me chercher via ce t\u00e9l\u00e9phone, soyez calme, je ne l\u2019\u00e9teindrai pas, Je ne vais pas me cacher, seulement ce que je voudrais vous dire c\u2019est que je ne suis pas un imb\u00e9cile, que je n\u2019ai aucun probl\u00e8me psychologique, pas du tout, que personne ne dit que je suis fou, je suis tout \u00e0 fait normal. Je ne mendie m\u00eame pas, je n\u2019ai pas faim. Je ne vais m\u00eame pas me suicider, que personne ne ment, chers Rwandais que je me suis suicid\u00e9, c\u2019est le seul suicide que je commets: venir et vouloir lib\u00e9rer les Rwandais. Je ne peux pas me suicider. Je vous ai dit que j\u2019\u00e9tais parent \u2013 mes enfants ont besoin de moi. Je n\u2019ai m\u00eame pas de maladie sp\u00e9cifique qui puisse me pousser \u00e0 m\u2019\u00e9puiser et \u00e0 me suicider.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiconque dirait cela mentirait. Pendant que je parle, je suis \u00e0 la maison, je suis dans le confinement, je ne sors pas, qu\u2019ils ne cherchent donc pas \u00e0 me courir dessus. Je suis vraiment d\u00e9sol\u00e9, je suis m\u00eame en bonne relation avec mes employ\u00e9s, ils ne vont pas me tuer, quoi qu\u2019il en soit qui va m\u2019arriver aura \u00e0 voir avec ce que je viens de dire, et je n\u2019ai pas peur parce que j\u2019ai dit en \u00e9tant pr\u00e9par\u00e9 que tout est possible et je l\u2019ai dit \u00e9tant tr\u00e8s fatigu\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quoi qu\u2019il puisse m\u2019arriver \u00e0 cette minute, j\u2019aurai r\u00e9v\u00e9l\u00e9 mes r\u00eaves de lib\u00e9ration des Rwandais, j\u2019aurai transmis le message que je veux transmettre. Et laissez-moi vous dire que m\u00eame si quelqu\u2019un pouvait me faire du mal et me tuer, demain na\u00eetrait quelqu\u2019un d\u2019autre comme moi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutes les personnes ne sont pas pr\u00eates \u00e0 accepter toutes choses et \u00e0 applaudir \u00e0 tout ce qui est dit. Non, il y aura des personnes qui verront de mauvaises choses et expliqueront qu\u2019elles sont mauvaises, surtout que le Rwanda que nous avons aujourd\u2019hui n\u2019a pas besoin d\u2019\u00eatre dirig\u00e9 par quelqu\u2019un, qui ressent en lui des id\u00e9es qu\u2019il est plus Hutus que d\u2019autres Hutus, debout pour les Hutus. Il n\u2019a pas besoin d\u2019\u00eatre dirig\u00e9 par un Tutsi qui repr\u00e9sente les Tutsi. Non plus, on ne s\u2019attend pas \u00e0 \u00eatre dirig\u00e9 par un autochtone qui repr\u00e9sente les autochtones. Le Rwanda n\u2019a pas besoin d\u2019un leader qui a une seule discrimination, qu\u2019elle soit bas\u00e9e sur la r\u00e9gion d\u2019o\u00f9 l\u2019on vient, qu\u2019elle soit bas\u00e9e sur la couleur de la peau, qu\u2019elle soit bas\u00e9e sur l\u2019ethnie, qu\u2019elle soit bas\u00e9e sur le sexe ou toute autre chose. .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Rwanda a besoin d\u2019\u00eatre dirig\u00e9 par quelqu\u2019un qui ressent de l\u2019amour pour les Rwandais en lui, qui a l\u2019esprit patriotique en lui, qui peut se battre pour leur pays si n\u00e9cessaire. Qui peut sacrifier sa vie pour les Rwandais si besoin est, qui ne se soucie pas seulement de lui-m\u00eame. Et surtout, un dirigeant qui respecte Dieu, qui a peur des yeux de Dieu, qui respecte Dieu, qui croit que Dieu lui demandera son peuple, qui croit que quoi qu\u2019il fasse, que ce soit bon ou mauvais, un jour, Dieu lui demandera des comptes, une personne qui respecte Dieu, qui a peur de Dieu et tremble devant Lui, qui croit ne pas pouvoir tuer les gens comme il veut. C\u2019est la personne dont le Rwanda a besoin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chers Rwandais, je ne souhaite pas prendre si longtemps, je ne veux pas parler de beaucoup de choses car je n\u2019ai m\u00eame pas la capacit\u00e9 de traverser des ennuis aujourd\u2019hui, mais ce que je sais, c\u2019est que peu importe combien de temps cela peut prendre, les probl\u00e8mes seront r\u00e9gl\u00e9s et les Rwandais se r\u00e9jouiront. Peu importe le temps que cela prendra, la paix pr\u00e9vaudra dans notre pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je conclus en vous remerciant et en vous souhaitant la protection de Dieu, que la paix de Dieu soit avec vous, et je vous souhaite de continuer \u00e0 vous prot\u00e9ger contre le coronavirus, mais en pensant \u00e0 d\u2019autres strat\u00e9gies \u00e0 utiliser pour que vous viviez sans \u00eatre tu\u00e9 par la d\u00e9pression ou le chagrin \u00e0 la maison et en respectant Dieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci beaucoup, s\u2019il y a d\u2019autres choses que je veux partager avec vous, par la gr\u00e2ce de Dieu; je suis encore en vie, je vais vous parler, parce que j\u2019aime beaucoup les Rwandais, que le Dieu c\u00e9leste vous b\u00e9nisse. Amen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>60 ans apr\u00e8s la r\u00e9volution rwandaise de 1959, une deuxi\u00e8me r\u00e9volution est d\u00e9clench\u00e9e par le discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryamugwiza. C\u2019\u00e9tait le 31 Janvier 2021, en deux semaines seulement, son discours sur sa chaine YouTube a battu tous les records rwandais avec plus de 200 000 visionnements. Pour le monde entier [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8648,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-8647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais - LeRwandais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais - LeRwandais\" \/>\n<meta property=\"og:description\" content=\"60 ans apr\u00e8s la r\u00e9volution rwandaise de 1959, une deuxi\u00e8me r\u00e9volution est d\u00e9clench\u00e9e par le discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryamugwiza. C\u2019\u00e9tait le 31 Janvier 2021, en deux semaines seulement, son discours sur sa chaine YouTube a battu tous les records rwandais avec plus de 200 000 visionnements. Pour le monde entier [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/\" \/>\n<meta property=\"og:site_name\" content=\"LeRwandais\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-17T16:42:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-17T16:51:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2021\/02\/Idamange.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"therwda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"therwda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"60 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/\"},\"author\":{\"name\":\"therwda\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7443e799cb2ddd036d77274bf6fc089\"},\"headline\":\"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais\",\"datePublished\":\"2021-02-17T16:42:36+00:00\",\"dateModified\":\"2021-02-17T16:51:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/\"},\"wordCount\":12094,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/Idamange.jpg\",\"articleSection\":[\"Opinion\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/\",\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/\",\"name\":\"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais - LeRwandais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/Idamange.jpg\",\"datePublished\":\"2021-02-17T16:42:36+00:00\",\"dateModified\":\"2021-02-17T16:51:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7443e799cb2ddd036d77274bf6fc089\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/Idamange.jpg\",\"contentUrl\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/Idamange.jpg\",\"width\":790,\"height\":566},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/\",\"name\":\"LeRwandais\",\"description\":\"Therwandan Journal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7443e799cb2ddd036d77274bf6fc089\",\"name\":\"therwda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g\",\"caption\":\"therwda\"},\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/author\\\/therwda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais - LeRwandais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/","og_locale":"fr_FR","og_type":"article","og_title":"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais - LeRwandais","og_description":"60 ans apr\u00e8s la r\u00e9volution rwandaise de 1959, une deuxi\u00e8me r\u00e9volution est d\u00e9clench\u00e9e par le discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryamugwiza. C\u2019\u00e9tait le 31 Janvier 2021, en deux semaines seulement, son discours sur sa chaine YouTube a battu tous les records rwandais avec plus de 200 000 visionnements. Pour le monde entier [&hellip;]","og_url":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/","og_site_name":"LeRwandais","article_published_time":"2021-02-17T16:42:36+00:00","article_modified_time":"2021-02-17T16:51:13+00:00","og_image":[{"width":790,"height":566,"url":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2021\/02\/Idamange.jpg","type":"image\/jpeg"}],"author":"therwda","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"therwda","Dur\u00e9e de lecture estim\u00e9e":"60 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#article","isPartOf":{"@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/"},"author":{"name":"therwda","@id":"https:\/\/www.therwandan.com\/fr\/#\/schema\/person\/e7443e799cb2ddd036d77274bf6fc089"},"headline":"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais","datePublished":"2021-02-17T16:42:36+00:00","dateModified":"2021-02-17T16:51:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/"},"wordCount":12094,"commentCount":0,"image":{"@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2021\/02\/Idamange.jpg","articleSection":["Opinion"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/","url":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/","name":"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais - LeRwandais","isPartOf":{"@id":"https:\/\/www.therwandan.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#primaryimage"},"image":{"@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2021\/02\/Idamange.jpg","datePublished":"2021-02-17T16:42:36+00:00","dateModified":"2021-02-17T16:51:13+00:00","author":{"@id":"https:\/\/www.therwandan.com\/fr\/#\/schema\/person\/e7443e799cb2ddd036d77274bf6fc089"},"breadcrumb":{"@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#primaryimage","url":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2021\/02\/Idamange.jpg","contentUrl":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2021\/02\/Idamange.jpg","width":790,"height":566},{"@type":"BreadcrumbList","@id":"https:\/\/www.therwandan.com\/fr\/discours-historique-et-prophetique-de-mme-yvonne-idamange-iryabagwiza-traduit-librement-et-ecrit-en-francais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.therwandan.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Discours historique et proph\u00e9tique de Mme Yvonne Idamange Iryabagwiza traduit librement et \u00e9crit en fran\u00e7ais"}]},{"@type":"WebSite","@id":"https:\/\/www.therwandan.com\/fr\/#website","url":"https:\/\/www.therwandan.com\/fr\/","name":"LeRwandais","description":"Therwandan Journal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.therwandan.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.therwandan.com\/fr\/#\/schema\/person\/e7443e799cb2ddd036d77274bf6fc089","name":"therwda","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g","caption":"therwda"},"url":"https:\/\/www.therwandan.com\/fr\/author\/therwda\/"}]}},"_links":{"self":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts\/8647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/comments?post=8647"}],"version-history":[{"count":2,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts\/8647\/revisions"}],"predecessor-version":[{"id":8650,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts\/8647\/revisions\/8650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/media\/8648"}],"wp:attachment":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/media?parent=8647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/categories?post=8647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/tags?post=8647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}