{"id":9006,"date":"2021-04-29T08:14:10","date_gmt":"2021-04-29T08:14:10","guid":{"rendered":"https:\/\/www.therwandan.com\/fr\/?p=9006"},"modified":"2021-04-29T08:14:13","modified_gmt":"2021-04-29T08:14:13","slug":"enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais","status":"publish","type":"post","link":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/","title":{"rendered":"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Par<strong>\u00a0<\/strong><a href=\"https:\/\/fr.sputniknews.com\/authors\/mbeko_patrick\/\"><strong>Patrick Mbeko<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le non-lieu rendu par les juges fran\u00e7ais dans l\u2019enqu\u00eate sur l\u2019attentat ayant co\u00fbt\u00e9 la vie au Pr\u00e9sident Habyarimana \u00e9tait-il fond\u00e9 en fait et en droit? Le politologue Charles Onana \u00e9met des doutes et pointe les dysfonctionnements d\u2019une justice fran\u00e7aise sous pression. D\u00e9cryptage pour Sputnik de Patrick Mbeko, sp\u00e9cialiste de l\u2019Afrique centrale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y a-t-il des gens en France qui tiennent \u00e0 ce que la v\u00e9rit\u00e9 sur l\u2019attentat qui a co\u00fbt\u00e9 la vie aux Pr\u00e9sidents Juv\u00e9nal Habyarimana du Rwanda et Cyprien Ntaryamira du Burundi, le 6 avril 1994, ne soit jamais connue? Y a-t-il des groupes d\u2019int\u00e9r\u00eats qui militent pour que les auteurs de cet acte terroriste, consid\u00e9r\u00e9 par les Nations unies comme l\u2019\u00e9v\u00e9nement d\u00e9clencheur du g\u00e9nocide au Rwanda, ne soient jamais appr\u00e9hend\u00e9s par la justice? La justice fran\u00e7aise, qui a rendu un non-lieu dans cette affaire apr\u00e8s 22 ann\u00e9es d\u2019instruction, s\u2019est-elle compromise?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est en tout cas ce qui ressort du livre-enqu\u00eate (Charles Onana,\u00a0<em>Enqu\u00eates sur un attentat<\/em>, L\u2019Artilleur, 2021) que vient de publier le politologue franco-camerounais Charles Onana, sp\u00e9cialiste de la r\u00e9gion des Grands Lacs.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/FrontPopOff\/status\/1385867851886735364?s=20\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Si le chemin qui m\u00e8ne \u00e0 la v\u00e9rit\u00e9 est souvent sem\u00e9 d\u2019obstacles et d\u2019emb\u00fbches, celui qui doit conduire \u00e0 la d\u00e9couverte de la v\u00e9rit\u00e9 sur l\u2019attentat du 6 avril 1994 s\u2019apparente \u00e0 une \u00e9quation math\u00e9matique difficile \u00e0 d\u00e9m\u00ealer. Charles Onana montre comment les interf\u00e9rences politiques jouent contre la v\u00e9rit\u00e9 et la justice dans ce dossier; il met \u00e0 nu les dysfonctionnements d\u2019une justice fran\u00e7aise sous pression, qui a choisi de faire de la politique plut\u00f4t que de dire le droit. Selon le politologue,&nbsp;<em>\u00abla derni\u00e8re d\u00e9cision de la justice fran\u00e7aise, en l\u2019occurrence celle rendue le 3 juillet 2020 par la cour d\u2019appel de Paris et concluant \u00e0 un non-lieu sur ce dossier, pose finalement plus de questions qu\u2019elle n\u2019\u00e9claire les familles de victimes et le grand public sur les auteurs de l\u2019attentat\u00bb.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019attentat et les premi\u00e8res enqu\u00eates<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019avion transportant le Pr\u00e9sident Habyarimana, son homologue burundais, leurs collaborateurs respectifs, ainsi que trois membres d\u2019\u00e9quipage fran\u00e7ais (le pilote, le co-pilote et le m\u00e9canicien navigant), a \u00e9t\u00e9 abattu par un missile, alors qu\u2019il amor\u00e7ait son atterrissage \u00e0 l\u2019a\u00e9roport Gr\u00e9goire Kayibanda (Kanombe, au Rwanda). Cet attentat a d\u00e9clench\u00e9 une spirale de massacres au cours de laquelle pr\u00e8s de 800.000 Rwandais ont trouv\u00e9 la mort. Qui sont les auteurs de cet acte terroriste qui a mis le feu aux poudres au Rwanda, avec des cons\u00e9quences incalculables qui se font toujours sentir dans toute la r\u00e9gion des Grands Lacs africains?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deux hypoth\u00e8ses s\u2019opposent: l\u2019une accusant les extr\u00e9mistes hutus et l\u2019autre pointant en direction du Front patriotique rwandais (FPR), la r\u00e9bellion tutsie dirig\u00e9e par l\u2019actuel Pr\u00e9sident rwandais Paul Kagame. En effet, si les rebelles tutsis et leurs relais occidentaux accusent les extr\u00e9mistes hutus d\u2019avoir abattu l\u2019avion de leur Pr\u00e9sident, assez \u00abmou\u00bb \u00e0 leurs yeux, pour commettre un g\u00e9nocide contre les Tutsis, les responsables hutus rwandais et un certain nombre d\u2019observateurs, pour leur part, imputent la responsabilit\u00e9 de l\u2019attentat au FPR, et plus particuli\u00e8rement \u00e0 Kagame, qui souhaitait se d\u00e9barrasser du chef de l\u2019\u00c9tat rwandais pour s\u2019emparer du pouvoir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour d\u00e9m\u00ealer le vrai du faux, Charles Onana plonge le lecteur dans les m\u00e9andres des enqu\u00eates men\u00e9es en Belgique, en Espagne, en France et au Tribunal p\u00e9nal international pour le Rwanda (TPIR). La sous-section investigation de l\u2019\u00e9tat-major de la force a\u00e9rienne belge avait ouvert une enqu\u00eate au lendemain du g\u00e9nocide parce que dix Casques bleus belges de la MINUAR (Mission des Nations unies pour l\u2019assistance au Rwanda) avaient \u00e9t\u00e9 tu\u00e9s au lendemain de l\u2019attentat. Ils \u00e9taient soup\u00e7onn\u00e9s par les FAR (Forces arm\u00e9es rwandaises) d\u2019y avoir pris part. En Espagne, le juge Fernando Andreu Merelles de l\u2019<em>Audiencia Nacional<\/em>, la plus haute juridiction du pays, s\u2019\u00e9tait saisi du dossier \u00e0 la demande des familles des victimes espagnoles assassin\u00e9es au Rwanda en 1997 par le FPR. En France, le juge antiterroriste Jean-Louis Brugui\u00e8re avait ouvert une information judiciaire, en 1998, \u00e0 la suite du d\u00e9p\u00f4t d\u2019une plainte avec constitution de partie civile \u00e9manant des membres des familles de l\u2019\u00e9quipage fran\u00e7ais qui avaient p\u00e9ri dans l\u2019attentat. S\u2019agissant du TPIR, le mandat que lui avait confi\u00e9 le Conseil de s\u00e9curit\u00e9 \u00e9tait de faire la lumi\u00e8re sur les \u00e9v\u00e9nements survenus au Rwanda entre le 1er janvier et le 31 d\u00e9cembre 1994. L\u2019enqu\u00eate du 6 avril en faisait donc partie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce que toutes ces enqu\u00eates ont en commun, c\u2019est d\u2019avoir point\u00e9 la possible responsabilit\u00e9 du FPR dans l\u2019attentat contre le Falcon 50 du Pr\u00e9sident Habyarimana. Aucune d\u2019entre elles n\u2019a retenu l\u2019hypoth\u00e8se d\u2019une attaque orchestr\u00e9e par les extr\u00e9mistes hutus. L\u2019enqu\u00eate de Charles Onana fourmille de d\u00e9tails sur la mani\u00e8re dont les investigations ont \u00e9t\u00e9 men\u00e9es et les preuves accumul\u00e9es par les juges belge, espagnol et fran\u00e7ais contre Paul Kagame et ses hommes. Plus encore, elle met en exergue le r\u00f4le combien important de certains acteurs internationaux dans l\u2019occultation de la v\u00e9rit\u00e9 sur la responsabilit\u00e9 du FPR dans l\u2019attentat.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les protecteurs de Paul Kagame \u00e0 la rescousse<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est au sein m\u00eame du TPIR, cens\u00e9 juger tous les crimes commis au Rwanda, y compris l\u2019attentat, que s\u2019est d\u2019abord organis\u00e9 l\u2019arbitraire. Non seulement la juridiction onusienne affirmait que l\u2019attentat ne faisait pas partie de son mandat, mais il est apparu qu\u2019elle avait dissimul\u00e9 une enqu\u00eate men\u00e9e par ses propres enqu\u00eateurs sur l\u2019attentat du 6 avril 1994. Le chef des enqu\u00eateurs, l\u2019Australien Michael Hourigan, aujourd\u2019hui d\u00e9c\u00e9d\u00e9, a fait \u00e9tat des pressions exerc\u00e9es sur lui par la procureur en chef du Tribunal, la Canadienne Louise Arbour, pour qu\u2019il mette fin \u00e0 ses investigations qui avaient identifi\u00e9 des membres du commando du FPR impliqu\u00e9s dans l\u2019attentat. Dans le livre d\u2019Onana, Hourigan raconte sa rencontre avec Madame Arbour \u00e0 La Haye:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00abJe lui ai montr\u00e9 le rapport que j\u2019avais pr\u00e9par\u00e9 pour notre rencontre. Il s\u2019agissait d\u2019un m\u00e9morandum interne qui contenait effectivement les informations que j\u2019avais obtenues de mes enqu\u00eateurs concernant l\u2019identit\u00e9 des membres du FPR impliqu\u00e9s dans l\u2019attentat du 6 avril 1994 ainsi que des d\u00e9tails op\u00e9rationnels de cet attentat. \u00c0 ma grande surprise, la procureur Louise Arbour s\u2019est referm\u00e9e comme une hu\u00eetre. Visage froiss\u00e9, l\u2019air grave, elle a commenc\u00e9 \u00e0 poser des questions sur la fiabilit\u00e9 des informations obtenues et m\u00eame sur la cr\u00e9dibilit\u00e9 des enqu\u00eateurs [&#8230;]. Mme Arbour a pris un ton s\u00e9v\u00e8re et m\u2019a lanc\u00e9, sans sourciller, que les investigations sur l\u2019attentat \u00e9taient d\u00e9sormais termin\u00e9es avant d\u2019ajouter qu\u2019\u00e0 son avis, elles ne faisaient pas partie du mandat du TPIR. Je n\u2019en croyais pas mes oreilles.\u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il convient de souligner que Louise Arbour a \u00e9t\u00e9 nomm\u00e9e au poste de procureur du TPIR\/TPIY sur recommandation de la secr\u00e9taire d\u2019\u00c9tat am\u00e9ricaine Madeleine Albright, soutien ind\u00e9fectible du FPR, comme le reste de l\u2019administration Clinton. La procureur canadienne avait-elle subi des pressions?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le t\u00e9moignage de Michael Hourigan ne laisse aucun doute sur l\u2019implication des \u00c9tats-Unis dans ce revirement de Louise Arbour. Ce n\u2019est qu\u2019une fois \u00e0 la retraite&nbsp;<a href=\"https:\/\/www.theglobeandmail.com\/news\/world\/kagame-government-supporters-complicated-un-efforts-to-investigate-crimes\/article32524359\/\" target=\"_blank\" rel=\"noreferrer noopener\">qu\u2019elle d\u00e9clarera<\/a>&nbsp;que Paul Kagame avait bloqu\u00e9 les enqu\u00eates, et que&nbsp;<em>\u00abcette affaire reste un tr\u00e8s grave \u00e9chec de la justice p\u00e9nale internationale\u00bb<\/em>. Sa successeur Carla Del Ponte sera \u00e9vinc\u00e9e du TPIR par les \u00c9tats-Unis et la Grande-Bretagne apr\u00e8s avoir tent\u00e9 d\u2019enqu\u00eater sur les crimes du FPR au Rwanda pendant le g\u00e9nocide. \u00c0 l\u2019instar de la procureur suisse, qui s\u2019est longuement confi\u00e9e \u00e0 Charles Onana sur ses p\u00e9rip\u00e9ties au TPIR, le juge espagnol Fernando Andreu Merelles a d\u00fb lui aussi faire face \u00e0 des pressions am\u00e9ricaines et \u00e0 des autorit\u00e9s britanniques peu scrupuleuses et d\u00e9termin\u00e9es \u00e0 prot\u00e9ger les pr\u00e9sum\u00e9s criminels du FPR contre lesquels la justice espagnole avait pourtant \u00e9mis 40 mandats d\u2019arr\u00eat internationaux pour leur implication dans les crimes de masse commis au Rwanda et en&nbsp;<em>R\u00e9publique d\u00e9mocratique du Congo<\/em>&nbsp;(RDC), y compris l\u2019attentat du 6 avril 1994.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019entr\u00e9e en sc\u00e8ne du \u00abr\u00e9seau\u00bb<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mais c\u2019est en France que s\u2019est organis\u00e9e la plus forte r\u00e9sistance face aux accusations visant Paul Kagame et le FPR pour leur implication dans l\u2019attentat du 6 avril 1994. Le juge Jean-Louis Brugui\u00e8re avait d\u00e9termin\u00e9 que le chef rebelle tutsi devenu Pr\u00e9sident du Rwanda \u00e9tait le commanditaire de l\u2019attentat. En 2006, il avait \u00e9mis des mandats d\u2019arr\u00eat contre neuf collaborateurs du Pr\u00e9sident Kagame. Estimant que ce dernier b\u00e9n\u00e9ficiait d\u2019une immunit\u00e9 due aux chefs d\u2019\u00c9tat, le juge fran\u00e7ais demanda au secr\u00e9taire g\u00e9n\u00e9ral de l\u2019Onu de saisir le TPIR afin de l\u2019inculper. Ce qui n\u2019arriva jamais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le gouvernement rwandais a qualifi\u00e9 l\u2019enqu\u00eate Brugui\u00e8re de politiquement motiv\u00e9e et a d\u00e9cid\u00e9 de rompre les relations diplomatiques avec la France. Les relations entre Paris et Kigali sont rest\u00e9es extr\u00eamement tendues&#8230; jusqu\u2019\u00e0 l\u2019\u00e9lection de l\u2019am\u00e9ricanophile Nicolas Sarkozy et la nomination au Quai d\u2019Orsay de l\u2019anglophile Kouchner. Ami de longue date de Paul Kagame, ce dernier va devenir la cheville ouvri\u00e8re du rapprochement entre Paris et Kigali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La premi\u00e8re phase de la man\u0153uvre, r\u00e9v\u00e8le Onana dans son livre, a \u00e9t\u00e9 de permettre au r\u00e9gime rwandais d\u2019avoir acc\u00e8s \u00e0 l\u2019enqu\u00eate Brugui\u00e8re. Une fois cet objectif atteint, la deuxi\u00e8me phase a consist\u00e9 \u00e0 sceller la \u00abr\u00e9conciliation\u00bb entre la France et le Rwanda, tout en court-circuitant le dossier judiciaire. Pour ce faire, tout un r\u00e9seau d\u2019individus, allant des diplomates et des magistrats aux agents d\u2019influence, en passant par des journalistes et des milieux associatifs fran\u00e7ais \u2014 tous acquis au r\u00e9gime de Kagame \u2014 vont travailler \u00e0 ce rapprochement, tout en cherchant \u00e0 torpiller l\u2019enqu\u00eate du juge Brugui\u00e8re. Philippe Bohn, agent d\u2019influence et membre de ce r\u00e9seau, explique dans son livre Agent d&rsquo;influence, \u00e9galement cit\u00e9 par Onana:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00abL\u2019une des forces du r\u00e9seau est de d\u00e9passer les contradictions des institutions et les prises de position officielles des \u00c9tats. Si certains, comme Bernard Kouchner, devenu ministre des Affaires \u00e9trang\u00e8res, ont contribu\u00e9 au rapprochement France-Rwanda et en ont compris l\u2019importance, nombre d\u2019intervenants, des deux bords, ont tent\u00e9 de s\u2019y opposer et de le faire capoter. Notre r\u00e9seau d\u2019influence mis au service du Pr\u00e9sident fran\u00e7ais et de son homologue rwandais a finalement contribu\u00e9 \u00e0 la r\u00e9alisation de cette r\u00e9conciliation.\u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce r\u00e9seau, dans lequel \u00e9voluent \u00e9galement plusieurs universitaires fran\u00e7ais, va se montrer particuli\u00e8rement entreprenant pour qu\u2019aucune autre version du g\u00e9nocide rwandais que celle de Kigali ne puisse prosp\u00e9rer en France. D\u00e9but avril, Ma\u00eetre Philippe Prigent, l\u2019avocat de Charles Onana, a port\u00e9 plainte au Conseil sup\u00e9rieur de l\u2019audiovisuel (CSA) contre France M\u00e9dias Monde et sa patronne Marie-Christine Saragosse. Il accuse deux associations appartenant \u00e0 ce r\u00e9seau, Survie et Ibuka, d&rsquo;\u00eatre discr\u00e8tement intervenues aupr\u00e8s de la pr\u00e9sidente de France M\u00e9dias Monde, Marie-Christine Saragosse, pour exiger la censure de Charles Onana sur les antennes de France 24 et RFI. Il accuse Madame Saragosse, qui est proche de l\u2019ancienne ministre des Affaires \u00e9trang\u00e8res du Rwanda, Louise Mushikiwabo, aujourd\u2019hui \u00e0 la t\u00eate de la Francophonie, d&rsquo;avoir acquiesc\u00e9 \u00e0 leur demande en les rassurant que le politologue franco-camerounais ne serait plus jamais invit\u00e9 dans les m\u00e9dias de France M\u00e9dias Monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plusieurs personnes issues du milieu universitaire et journalistique sont ulc\u00e9r\u00e9es par la censure qui r\u00e8gne dans les grands m\u00e9dias fran\u00e7ais sur le Rwanda, tel qu\u2019il ressort des \u00e9changes avec l\u2019auteur de ces lignes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La myopie volontaire des juges fran\u00e7ais<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sur la sc\u00e8ne judiciaire fran\u00e7aise, les choses se sont acc\u00e9l\u00e9r\u00e9es. Si la strat\u00e9gie imagin\u00e9e par un groupe de fonctionnaires du Quai d\u2019Orsay sous l\u2019impulsion du ministre Kouchner a permis au gouvernement rwandais d\u2019avoir acc\u00e8s au dossier de l\u2019instruction (Brugui\u00e8re), la reprise du dossier par les juges Marc Tr\u00e9vidic et Nathalie Poux, puis par le juge Jean-Marc Herbaut, a sonn\u00e9 le d\u00e9but d\u2019une nouvelle \u00e8re dans l\u2019enqu\u00eate sur l\u2019attentat du 6 avril 1994 en France.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fait, les successeurs du juge Brugui\u00e8re vont donner une nouvelle orientation \u00e0 l\u2019instruction. En 2012, les juges Tr\u00e9vidic et Poux produisent un rapport balistique et acoustique controvers\u00e9 sur l\u2019origine du tir du missile qui a abattu le Falcon 50, le 6 avril 1994. La presse fran\u00e7aise s\u2019enflamme et fait dire au rapport ce qu\u2019il ne dit pas, \u00e0 l\u2019id\u00e9e que l\u2019avion d\u2019Habyarimana serait abattu par les extr\u00e9mistes hutus, leur faisant porter au passage la responsabilit\u00e9 du g\u00e9nocide. Or Tr\u00e9vidic et Poux n\u2019ont rien dit tel. En fait, ils ont tent\u00e9 de semer le doute sur l\u2019origine du tir du missile qui a abattu l\u2019avion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s\u2019agit l\u00e0 d\u2019un enjeu majeur dans la compr\u00e9hension et l\u2019interpr\u00e9tation des \u00e9v\u00e9nements survenus au Rwanda en 1994. Comme l\u2019a sugg\u00e9r\u00e9 la procureur suisse Carla Del Ponte dans une interview donn\u00e9e il y a plusieurs ann\u00e9es, \u00abs\u2019il s\u2019av\u00e8re que c\u2019est le FPR qui a abattu l\u2019avion, l\u2019histoire du g\u00e9nocide devrait \u00eatre r\u00e9\u00e9crite\u00bb. Or l\u2019histoire officielle avait d\u00e9j\u00e0 d\u00e9cr\u00e9t\u00e9, avant m\u00eame la cr\u00e9ation du TPIR, que les Hutus avaient commis un g\u00e9nocide contre les Tutsis. Par cons\u00e9quent, attribuer la paternit\u00e9 de l\u2019attentat au FPR bousculerait s\u00e9rieusement la doxa, quitte \u00e0 remettre les compteurs de l\u2019historiographie officielle \u00e0 z\u00e9ro. Les juges Tr\u00e9vidic et Poux en \u00e9taient conscients; raison pour laquelle ils ont produit le rapport balistique controvers\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_93519\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/EadibVSnUh4?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, plusieurs observateurs et connaisseurs du dossier rwandais, et non des moindres, ont remis en question la scientificit\u00e9 du rapport command\u00e9 par les magistrats fran\u00e7ais, que d\u2019aucuns ont d\u2019ailleurs soup\u00e7onn\u00e9s de vouloir torpiller d\u00e9finitivement le dossier Brugui\u00e8re. \u00c0 l\u2019auteur de ces lignes, le colonel Luc Marchal, qui a command\u00e9 les Casques bleus belges \u00e0 Kigali, a d\u00e9clar\u00e9:&nbsp;<em>\u00abSi on cherchait \u00e0 torpiller l\u2019enqu\u00eate du juge Brugui\u00e8re, on ne s\u2019y prendrait pas autrement.\u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rappelons que, en ce qui concerne la responsabilit\u00e9 du FPR dans l\u2019attentat, la plupart des \u00e9l\u00e9ments d\u2019enqu\u00eate rassembl\u00e9s par le juge Jean-Louis Brugui\u00e8re ont \u00e9t\u00e9 corrobor\u00e9s aussi bien par les enqu\u00eates conduites en Espagne et en Belgique que par celles men\u00e9es par le TPIR. Comment d\u00e8s lors comprendre l\u2019orientation donn\u00e9e \u00e0 cette affaire par les successeurs de Brugui\u00e8re?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le plus troublant dans ce dossier, c\u2019est que les juges fran\u00e7ais se sont montr\u00e9s particuli\u00e8rement hostiles \u00e0 toute documentation pointant en direction du FPR, se contentant de reprendre les conclusions d\u2019un rapport probl\u00e9matique sur l\u2019attentat (rapport de la commission Mutsinzi) r\u00e9dig\u00e9 par le r\u00e9gime de Kigali et contest\u00e9 par plusieurs experts s\u00e9rieux. Ils n\u2019ont pas non plus cherch\u00e9 \u00e0 entendre les t\u00e9moins \u00e0 charge les plus cr\u00e9dibles, entre autres le colonel Luc Marchal ou encore les anciens hauts responsables du FPR qui \u00e9taient au c\u0153ur de la conjuration ayant conduit \u00e0 l\u2019attentat. Plus grave, ils ont fait preuve d\u2019une grave n\u00e9gligence en convoquant un t\u00e9moin \u00e0 Paris sans assurer convenablement sa protection. Il s\u2019agit d\u2019\u00c9mile Gafirita, un ancien du FPR qui disait d\u00e9tenir des informations sur la pr\u00e9paration de l\u2019attentat. Celui-ci a \u00e9t\u00e9 finalement\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.marianne.net\/agora\/tribunes-libres\/attentat-contre-habyarimana-et-genocide-rwandais-deconstruction-d-une\" target=\"_blank\">kidnapp\u00e9 au Kenya<\/a>\u00a0par les sbires du FPR et a \u00e9t\u00e9 tu\u00e9. Son corps n\u2019a jamais \u00e9t\u00e9 retrouv\u00e9.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">Cette affaire Emile Gafirita demeure une honte pour la justice fran\u00e7aise ainsi que pour le minist\u00e8re des affaires \u00e9trang\u00e8res. Ce t\u00e9moin cl\u00e9 n&#39;a pas b\u00e9n\u00e9fici\u00e9 de la protection qui lui \u00e9tait due. <a href=\"https:\/\/t.co\/EgQn7AAD1A\">https:\/\/t.co\/EgQn7AAD1A<\/a><\/p>&mdash; Herv\u00e9 Cheuzeville (@CheuzevilleH) <a href=\"https:\/\/twitter.com\/CheuzevilleH\/status\/1191273768129306625?ref_src=twsrc%5Etfw\">November 4, 2019<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Une justice fran\u00e7aise politiquement transmissible<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le livre de Charles Onana interroge sur la s\u00e9rie de dysfonctionnements qui ont jalonn\u00e9 le fonctionnement de la justice fran\u00e7aise dans le dossier relatif \u00e0 l\u2019attentat du 6 avril 1994 au Rwanda. Il interroge \u00e9galement tant sur le s\u00e9rieux et le professionnalisme des juges fran\u00e7ais que sur le caract\u00e8re hautement politique de leurs investigations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce que l\u2019enqu\u00eate du politologue franco-camerounais r\u00e9v\u00e8le surtout, c\u2019est que le r\u00e9tablissement des relations diplomatiques entre la France et le Rwanda s\u2019est fait non seulement sur le dos de la v\u00e9rit\u00e9, mais aussi et surtout sur celui de la justice. Le dossier de l\u2019attentat a progress\u00e9 au gr\u00e9 des embellies et des passions caract\u00e9ris\u00e9es par les soubresauts des relations difficiles entre Paris et Kigali. Au paroxysme durant le quinquennat Sarkozy, les relations entre les deux capitales ont connu un moment de froideur sous Fran\u00e7ois Hollande, avant de se \u00abr\u00e9chauffer\u00bb sous le quinquennat d\u2019Emmanuel Macron, qui a d\u00e9cid\u00e9 de faire de Paul Kagame un interlocuteur \u00abpivot\u00bb en Afrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019enqu\u00eate fran\u00e7aise sur l\u2019attentat du 6 avril 1994 est un \u00e9norme scandale judiciaire qui refuse de dire son nom. Deux chefs d\u2019\u00c9tat africains, leurs collaborateurs ainsi que trois membres d\u2019\u00e9quipage fran\u00e7ais de l\u2019avion qui les transportait ont \u00e9t\u00e9 sacrifi\u00e9s sur l\u2019autel des conciliabules et des relations diplomatiques entre la France et un r\u00e9gime africain d\u00e9cri\u00e9 par les organisations des droits de l\u2019homme.&nbsp;<em>\u00abC\u2019est la triste r\u00e9alit\u00e9 de la justice fran\u00e7aise\u00bb<\/em>, soupire un v\u00e9t\u00e9ran de la magistrature parisienne qui s\u2019est confi\u00e9 \u00e0 Onana. Et de poursuivre:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00abSi vous saviez la propension \u00e0 la couardise de certains magistrats, si vous saviez le nombre de carri\u00e9ristes qui se bousculent dans cet univers, si vous saviez jusqu\u2019o\u00f9 certains vont parfois&#8230;Vous comprendriez plus facilement le fiasco que l\u2019on conna\u00eet dans un grand nombre d\u2019affaires judiciaires de cette importance! H\u00e9las, le dossier de l\u2019attentat du 6 avril au Rwanda n\u2019en est que la meilleure illustration.\u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fin d\u00e9cembre 2018, le juge Jean-Marc Herbaut, qui a succ\u00e9d\u00e9 \u00e0 Marc Tr\u00e9vidic, a prononc\u00e9 le non-lieu en faveur des proches de Paul Kagame, mettant ainsi fin \u00e0 deux d\u00e9cennies d\u2019enqu\u00eate particuli\u00e8rement tortueuse, ponctu\u00e9e de graves distorsions, d\u2019ing\u00e9rences en tout genre. La d\u00e9cision a \u00e9t\u00e9 confirm\u00e9e par la cour d\u2019appel de Paris. Les parties civiles ont introduit un pourvoi en cassation pour contester cet arr\u00eat, en esp\u00e9rant s\u00fbrement que la politique ne s\u2019invitera pas de nouveau dans le d\u00e9bat judiciaire&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/fr.sputniknews.com\/afrique\/202103291045415061-genocide-rwandais-un-rapport-francais-politiquement-charge\/\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00a0Patrick Mbeko Le non-lieu rendu par les juges fran\u00e7ais dans l\u2019enqu\u00eate sur l\u2019attentat ayant co\u00fbt\u00e9 la vie au Pr\u00e9sident Habyarimana \u00e9tait-il fond\u00e9 en fait et en droit? Le politologue Charles Onana \u00e9met des doutes et pointe les dysfonctionnements d\u2019une justice fran\u00e7aise sous pression. D\u00e9cryptage pour Sputnik de Patrick Mbeko, sp\u00e9cialiste de l\u2019Afrique centrale. Y a-t-il [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"class_list":["post-9006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais? - LeRwandais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais? - LeRwandais\" \/>\n<meta property=\"og:description\" content=\"Par\u00a0Patrick Mbeko Le non-lieu rendu par les juges fran\u00e7ais dans l\u2019enqu\u00eate sur l\u2019attentat ayant co\u00fbt\u00e9 la vie au Pr\u00e9sident Habyarimana \u00e9tait-il fond\u00e9 en fait et en droit? Le politologue Charles Onana \u00e9met des doutes et pointe les dysfonctionnements d\u2019une justice fran\u00e7aise sous pression. D\u00e9cryptage pour Sputnik de Patrick Mbeko, sp\u00e9cialiste de l\u2019Afrique centrale. Y a-t-il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/\" \/>\n<meta property=\"og:site_name\" content=\"LeRwandais\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-29T08:14:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-29T08:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2017\/05\/Mbeko.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"therwda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"therwda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/\"},\"author\":{\"name\":\"therwda\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7443e799cb2ddd036d77274bf6fc089\"},\"headline\":\"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais?\",\"datePublished\":\"2021-04-29T08:14:10+00:00\",\"dateModified\":\"2021-04-29T08:14:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/\"},\"wordCount\":3262,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/Mbeko.jpg\",\"articleSection\":[\"Analyse\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/\",\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/\",\"name\":\"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais? - LeRwandais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/Mbeko.jpg\",\"datePublished\":\"2021-04-29T08:14:10+00:00\",\"dateModified\":\"2021-04-29T08:14:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7443e799cb2ddd036d77274bf6fc089\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/Mbeko.jpg\",\"contentUrl\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/Mbeko.jpg\",\"width\":500,\"height\":500,\"caption\":\"Patrick Mbeko\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/\",\"name\":\"LeRwandais\",\"description\":\"Therwandan Journal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7443e799cb2ddd036d77274bf6fc089\",\"name\":\"therwda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g\",\"caption\":\"therwda\"},\"url\":\"https:\\\/\\\/www.therwandan.com\\\/fr\\\/author\\\/therwda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais? - LeRwandais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/","og_locale":"fr_FR","og_type":"article","og_title":"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais? - LeRwandais","og_description":"Par\u00a0Patrick Mbeko Le non-lieu rendu par les juges fran\u00e7ais dans l\u2019enqu\u00eate sur l\u2019attentat ayant co\u00fbt\u00e9 la vie au Pr\u00e9sident Habyarimana \u00e9tait-il fond\u00e9 en fait et en droit? Le politologue Charles Onana \u00e9met des doutes et pointe les dysfonctionnements d\u2019une justice fran\u00e7aise sous pression. D\u00e9cryptage pour Sputnik de Patrick Mbeko, sp\u00e9cialiste de l\u2019Afrique centrale. Y a-t-il [&hellip;]","og_url":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/","og_site_name":"LeRwandais","article_published_time":"2021-04-29T08:14:10+00:00","article_modified_time":"2021-04-29T08:14:13+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2017\/05\/Mbeko.jpg","type":"image\/jpeg"}],"author":"therwda","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"therwda","Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#article","isPartOf":{"@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/"},"author":{"name":"therwda","@id":"https:\/\/www.therwandan.com\/fr\/#\/schema\/person\/e7443e799cb2ddd036d77274bf6fc089"},"headline":"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais?","datePublished":"2021-04-29T08:14:10+00:00","dateModified":"2021-04-29T08:14:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/"},"wordCount":3262,"commentCount":1,"image":{"@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2017\/05\/Mbeko.jpg","articleSection":["Analyse"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/","url":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/","name":"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais? - LeRwandais","isPartOf":{"@id":"https:\/\/www.therwandan.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#primaryimage"},"image":{"@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2017\/05\/Mbeko.jpg","datePublished":"2021-04-29T08:14:10+00:00","dateModified":"2021-04-29T08:14:13+00:00","author":{"@id":"https:\/\/www.therwandan.com\/fr\/#\/schema\/person\/e7443e799cb2ddd036d77274bf6fc089"},"breadcrumb":{"@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#primaryimage","url":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2017\/05\/Mbeko.jpg","contentUrl":"https:\/\/www.therwandan.com\/fr\/wp-content\/uploads\/sites\/2\/2017\/05\/Mbeko.jpg","width":500,"height":500,"caption":"Patrick Mbeko"},{"@type":"BreadcrumbList","@id":"https:\/\/www.therwandan.com\/fr\/enquete-sur-lattentat-du-6-avril-1994-un-scandale-judiciaire-francais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.therwandan.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Enqu\u00eate sur l\u2019attentat du 6 avril 1994: un scandale judiciaire fran\u00e7ais?"}]},{"@type":"WebSite","@id":"https:\/\/www.therwandan.com\/fr\/#website","url":"https:\/\/www.therwandan.com\/fr\/","name":"LeRwandais","description":"Therwandan Journal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.therwandan.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.therwandan.com\/fr\/#\/schema\/person\/e7443e799cb2ddd036d77274bf6fc089","name":"therwda","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/638fa5c55f77e8c27e06281ee4e9bf4c68b2dd109665c9846f31bf16d42f64a5?s=96&d=mm&r=g","caption":"therwda"},"url":"https:\/\/www.therwandan.com\/fr\/author\/therwda\/"}]}},"_links":{"self":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts\/9006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/comments?post=9006"}],"version-history":[{"count":1,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts\/9006\/revisions"}],"predecessor-version":[{"id":9007,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/posts\/9006\/revisions\/9007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/media\/5003"}],"wp:attachment":[{"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/media?parent=9006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/categories?post=9006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.therwandan.com\/fr\/wp-json\/wp\/v2\/tags?post=9006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}